{"id":11277,"date":"2022-10-05T10:00:00","date_gmt":"2022-10-05T08:00:00","guid":{"rendered":"https:\/\/www.legalsmart.de\/blog\/?p=11277"},"modified":"2022-09-26T11:24:10","modified_gmt":"2022-09-26T09:24:10","slug":"naechstes-urteil-gegen-fitness-kette","status":"publish","type":"post","link":"https:\/\/www.legalsmart.de\/blog\/naechstes-urteil-gegen-fitness-kette\/","title":{"rendered":"N\u00e4chstes Urteil gegen Fitness-Kette"},"content":{"rendered":"\n<p>Fordern Sie Ihre Beitr\u00e4ge f\u00fcr das Fitnessstudio zur\u00fcck! Es gibt ein neues Urteil gegen eine Fitnesskette. Am 29.08.2022 best\u00e4tigte das Kammergericht, dass Fitnessstudios die Vertr\u00e4ge nicht einseitig verl\u00e4ngern d\u00fcrfen. Am 04.05.2022 hat der Bundesgerichtshof (BGH), Az. XII 64\/21, entschieden, dass die gezahlten Beitr\u00e4ge zur\u00fcckzuerstatten sind, wenn es keine Gegenleistung der Fitnessstudios w\u00e4hrend der Schlie\u00dfzeit gab.<\/p>\n\n\n\n<p>Alles was Sie zum Thema R\u00fcckzahlungsanspr\u00fcche bei Fitnessstudios wissen m\u00fcssen, erfahren Sie hier:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>BGH: Fit\u00adness\u00adstu\u00addios m\u00fcssen Mit\u00adg\u00adlieds\u00adbei\u00adtr\u00e4ge zur\u00fcck\u00adzahlen<\/strong><\/h3>\n\n\n\n<p>Der Bundesgerichtshof hat entschieden, dass Mitgliedsbeitr\u00e4ge in Fitnessstudios zur\u00fcckgezahlt werden m\u00fcssen, wenn die Studios coronabedingt geschlossen waren. Auch darf die Laufzeit des Vertrages nicht einfach nach hinten hinaus verl\u00e4ngert werden. (BGH, Urt. v. 04.05.2022, Az. <a href=\"https:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=XII%20ZR%2064\/21\" title=\"BGH, 04.05.2022 - XII ZR 64\/21: Zahlungspflicht bei coronabedingter Schlie&szlig;ung eines Fitnessstu...\">XII ZR 64\/21<\/a>)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>R\u00fcckzahlungspflicht f\u00fcr Betreiber&nbsp;<\/strong><\/h3>\n\n\n\n<p>Der BGH hat Anfang Mai entschieden, dass die Betreiber zur R\u00fcckzahlung von Beitr\u00e4gen f\u00fcr den Zeitraum verpflichtet sind, wenn die Studios coronabedingt geschlossen waren.&nbsp;<\/p>\n\n\n\n<p>Die Betreiber der Studios haben jedoch f\u00fcr die Monate der Schlie\u00dfung weiterhin Abbuchungen der Mitgliedsbeitr\u00e4ge durchgef\u00fchrt. Das ist rechtswidrig.<\/p>\n\n\n\n<p><strong>Rechtstipp<\/strong>: Der R\u00fcckzahlungsanpruch ergibt sich aus <a href=\"https:\/\/dejure.org\/gesetze\/BGB\/275.html\" title=\"&sect; 275 BGB: Ausschluss der Leistungspflicht\">\u00a7\u00a7 275 Abs. 1<\/a>, <a href=\"https:\/\/dejure.org\/gesetze\/BGB\/326.html\" title=\"&sect; 326 BGB: Befreiung von der Gegenleistung und R&uuml;cktritt beim Ausschluss der Leistungspflicht\">\u00a7 326 Abs. 1 Satz 1 und Abs. 4<\/a>, <a href=\"https:\/\/dejure.org\/gesetze\/BGB\/346.html\" title=\"&sect; 346 BGB: Wirkungen des R&uuml;cktritts\">\u00a7 346 Abs. 1<\/a> B\u00fcrgerliches Gesetzbuch (BGB)<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Hauptleistungspflicht war nicht erf\u00fcllbar&nbsp;<\/strong><\/h3>\n\n\n\n<p>Fitnessstudios konnten den Kunden keine vergleichbare M\u00f6glichkeit anbieten (dazu z\u00e4hlt auch kein Online-Traningsangebot), sodass die Erf\u00fcllung der Hauptleistungspflicht ausgeschlossen war. Es lag auch kein Fall einer vor\u00fcbergehenden Unm\u00f6glichkeit vor, da die Leistungserbringung auch nicht nachgeholt werden kann. \u201e<em>Der Zweck eines Fitnessstudiovertrags liege gerade&nbsp;in der regelm\u00e4\u00dfigen sportlichen Bet\u00e4tigung.&nbsp;Daher sei gerade die regelm\u00e4\u00dfige und ganzj\u00e4hrige \u00d6ffnung&nbsp;des Studios von entscheidender Bedeutung.&nbsp;Kann der Betreiber des Fitnessstudios w\u00e4hrend der Vertragslaufzeit&nbsp;die Nutzung des Studios zeitweise nicht gew\u00e4hren, etwa&nbsp;&#8211; wie hier &#8211; wegen hoheitlicher&nbsp;Ma\u00dfnahmen, kann der Vertragszweck f\u00fcr den Zeitraum der Schlie\u00dfung nicht erreicht werden<\/em>.\u201c<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Keine Vertragsverl\u00e4ngerung<\/strong><\/h3>\n\n\n\n<p>Die Betreiber von Fitnessstudios wollten oftmals auf eine Vetragssverl\u00e4ngerung hinwirken. Jedoch wurde auch das vom zw\u00f6lften Zivilsenat abgelehnt. Rechtlich gesehen w\u00fcrde die Unm\u00f6glichkeit nach <a href=\"https:\/\/dejure.org\/gesetze\/BGB\/275.html\" title=\"&sect; 275 BGB: Ausschluss der Leistungspflicht\">\u00a7 275 Abs. 1 BGB<\/a> mit <a href=\"https:\/\/dejure.org\/gesetze\/BGB\/313.html\" title=\"&sect; 313 BGB: St&ouml;rung der Gesch&auml;ftsgrundlage\">\u00a7 313 BGB<\/a>, der St\u00f6rung der Gesch\u00e4ftsgrundlage, entgegenstehen.&nbsp;<\/p>\n\n\n\n<p>Ein Anspruch auf die begehrte Vertragsanpassung scheidet auch deshalb aus, weil mit <a href=\"https:\/\/dejure.org\/gesetze\/EGBGB\/240.html\" title=\"Art. 240 EGBGB: (weggefallen)\">Art. 240<\/a> \u00a7 5 Abs. 2 EGBGB eine speziellere Vorschrift besteht, die im vorliegenden Fall einem R\u00fcckgriff auf die allgemeinen Grunds\u00e4tze zur Vertragsanpassung wegen St\u00f6rung der Gesch\u00e4ftsgrundlage entgegensteht.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Muss ich Gutscheine akzeptieren?&nbsp;<\/strong><\/h3>\n\n\n\n<p>Zwar galt seit dem 20.05.2020 allerdings eine Ausnahme zu dem grunds\u00e4tzlich bestehenden R\u00fcckzahlungsanspruch. Den Anbietern ist die M\u00f6glichkeit gegeben worden, Gutscheine auszustellen, anstatt Beitr\u00e4ge zu erstatten. Das bedeutet, dass die Studios Ihnen Gutscheine ausstellen d\u00fcrfen, wenn Sie bereits get\u00e4tigte Zahlungen zur\u00fcckverlangen.<\/p>\n\n\n\n<p><strong>Achtung<\/strong>: Das hei\u00dft aber nicht, dass Sie ihr Geld nicht wiederbekommen: Diese M\u00f6glichkeit war gem\u00e4\u00df Artikel\u00a0<a href=\"https:\/\/dejure.org\/gesetze\/EGBGB\/240.html\" target=\"_blank\" rel=\"noreferrer noopener\">240<\/a>\u00a0<a href=\"https:\/\/dejure.org\/gesetze\/EGBGB\/5.html\" title=\"Art. 5 EGBGB: Personalstatut\">\u00a7 5 Abs. 5 Nr. 2<\/a> des Einf\u00fchrungsgesetzes zum B\u00fcrgerlichen Gesetzbuch (EGBGB) befristet.\u00a0<strong>Wenn Sie diese Gutscheine nicht bis zum 31.12.2021 eingel\u00f6st haben, steht Ihnen wieder ein Auszahlungsanspruch gegen Ihr Fitnessstudio zu.\u00a0<\/strong>Eine Pflicht zur Einl\u00f6sung gibt es nicht.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Fazit<\/strong><\/h3>\n\n\n\n<p>Wir berichteten schon im Juli 2021 \u00fcber Fitnessstudios, die Kundenrechte verwehren. Daher best\u00e4tigt der BGH unsere Rechtsauffassung im vollen Umfang.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Damit Sie Ihre Beitr\u00e4ge zur\u00fcckfordern k\u00f6nnen, stellen wir Ihnen hier ein Musterschreiben bereit:<\/h4>\n\n\n\n<p>(Absender\/ eigene Adresse)<\/p>\n\n\n\n<p>(Anschrift des Fitnessstudios)&nbsp;<\/p>\n\n\n\n<p>(Ort, Datum)<\/p>\n\n\n\n<p><strong>Vertragsnr\/ Kundennr.:<\/strong><\/p>\n\n\n\n<p>Sehr geehrte Damen und Herren,<\/p>\n\n\n\n<p>Sie ziehen meine monatlichen Mitgliedsbeitr\u00e4ge im Lastschriftverfahren ein. In der Zeit vom (<em>Datum bitte eintragen<\/em>) bis (<em>Datum bitte eintragen<\/em>) musste das Fitnessstudio aufgrund der Ma\u00dfnahmen zur Bek\u00e4mpfung der COVID-19-Pandemie schlie\u00dfen. Die Monatsbeitr\u00e4ge f\u00fcr diesen Zeitraum haben Sie jedoch weiter eingezogen.<\/p>\n\n\n\n<p>Nach meiner K\u00fcndigung haben Sie die Schlie\u00dfungszeit an das Vertragsende angeh\u00e4ngt, anstatt mir die Mitgliedsbeitr\u00e4ge wie gew\u00fcnscht auszuzahlen. Damit war ich nicht einverstanden. Dies habe ich Ihnen mit Schreiben \/ E-Mail vom (Datum bitte eintragen) mitgeteilt.<\/p>\n\n\n\n<p>Ich nehme Bezug auf das Urteil des Bundesgerichtshofs vom 04. Mai 2022 (AZ. <a href=\"https:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=XII%20ZR%2064\/21\" title=\"BGH, 04.05.2022 - XII ZR 64\/21: Zahlungspflicht bei coronabedingter Schlie&szlig;ung eines Fitnessstu...\">XII ZR 64\/21<\/a>) und fordere Sie auf, die zu viel gezahlten Beitr\u00e4ge in H\u00f6he von (<em>Summe einf\u00fcgen)<\/em>&nbsp;zu erstatten und auf mein Konto (<em>IBAN<\/em>) bei der (<em>Name der Bank und BIC<\/em>) zu \u00fcberweisen.&nbsp;<\/p>\n\n\n\n<p>Die R\u00fcckzahlung erwarte ich bis zum (<em>Datum f\u00fcr eine Frist einf\u00fcgen, \u00fcblich sind 14 Tage).<\/em><\/p>\n\n\n\n<p>Mit freundlichen Gr\u00fc\u00dfen&nbsp;<\/p>\n\n\n\n<p>(<em>Name und Unterschrift<\/em>)<\/p>\n\n\n\n<p>Falls Ihnen ein Gutschein ausgestellt wurde, und Sie diesen nicht eingel\u00f6st haben, k\u00f6nnte Ihnen folgendes Musterschreiben helfen:<\/p>\n\n\n\n<p>Am&nbsp;<em>(Ausstellungsdatum des Gutscheins)&nbsp;<\/em>haben Sie mir einen Gutschein f\u00fcr die Schlie\u00dfzeiten w\u00e4hrend der Corona-Pandemie ausgestellt.&nbsp;<\/p>\n\n\n\n<p>Diesen habe ich nicht eingel\u00f6st. Ich fordere Sie daher auf, mir den gesamten Betrag des Gutscheins von&nbsp;<em>(Summe einf\u00fcgen)&nbsp;<\/em>Euro zu erstatten und diesen auf mein Konto&nbsp;<em>(IBAN)&nbsp;<\/em>bei der&nbsp;<em>(Name der Bank und BIC)&nbsp;<\/em>zu \u00fcberweisen. Die R\u00fcckzahlung erwarte ich bis zum&nbsp;<em>(maximal 14 Tage in der Zukunft)<\/em>.&nbsp;<\/p>\n\n\n\n<p>Der&nbsp;Bundesgerichtshofs hat mit Urteil vom 4. Mai 2022 (Az. <a href=\"https:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=XII%20ZR%2064\/21\" title=\"BGH, 04.05.2022 - XII ZR 64\/21: Zahlungspflicht bei coronabedingter Schlie&szlig;ung eines Fitnessstu...\">XII ZR 64\/21<\/a>) entschieden, dass der Zweck eines Fitnessstudiovertrags in der regelm\u00e4\u00dfigen sportlichen Bet\u00e4tigung liegt. Bei einem Fitnessstudiovertrag mit mehrmonatiger fester Laufzeit, so wie in meinem Fall&nbsp;<em>(Ihre Kundennummer),&nbsp;<\/em>ist gerade die regelm\u00e4\u00dfige und ganzj\u00e4hrige \u00d6ffnung und Nutzbarkeit des Studios von entscheidender Bedeutung. Wenn Ihr Betrieb den Zutritt nicht mehr gew\u00e4hren kann, wird der Vertragszweck, so das Urteil des Bundesgerichtshofs, nicht erreicht. Diese geschuldete Leistung kann wegen des Zeitablaufs nicht nachgeholt werden.&nbsp;<\/p>\n\n\n\n<p>Anbei sende Ihnen eine Kopie des Gutscheins zu.<\/p>\n\n\n\n<p>Mit freundlichen Gr\u00fc\u00dfen&nbsp;<\/p>\n\n\n\n<p>(<em>Name und Unterschrift<\/em>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fordern Sie Ihre Beitr\u00e4ge f\u00fcr das Fitnessstudio zur\u00fcck! Es gibt ein neues Urteil gegen eine Fitnesskette. Am 29.08.2022 best\u00e4tigte das Kammergericht, dass Fitnessstudios die Vertr\u00e4ge nicht einseitig verl\u00e4ngern d\u00fcrfen. Am 04.05.2022 hat der Bundesgerichtshof (BGH), Az. XII 64\/21, entschieden, dass die gezahlten Beitr\u00e4ge zur\u00fcckzuerstatten sind, wenn es keine Gegenleistung der Fitnessstudios w\u00e4hrend der Schlie\u00dfzeit gab. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[8238,8240,8049,988,6141,2093,8239,3098,8052],"class_list":["post-11277","post","type-post","status-publish","format-standard","hentry","category-zivilrecht","tag-29-08-2022","tag-31-12-2021","tag-az-xii-zr-64-21","tag-bgh","tag-gutscheine","tag-kammergericht","tag-keine-vertragsverlaengerung","tag-ruckzahlungsanspruch","tag-urt-v-04-05-2022"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>N\u00e4chstes Urteil gegen Fitness-Kette | LEGAL SMART Online Blog<\/title>\n<meta name=\"description\" content=\"Fordern Sie Ihre Beitr\u00e4ge f\u00fcr das Fitnessstudio zur\u00fcck! Es gibt ein neues h\u00f6chstrichterliches Urteil gegen eine Fitnesskette.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.legalsmart.de\/blog\/naechstes-urteil-gegen-fitness-kette\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"N\u00e4chstes Urteil gegen Fitness-Kette | LEGAL SMART Online Blog\" \/>\n<meta property=\"og:description\" content=\"Fordern Sie Ihre Beitr\u00e4ge f\u00fcr das Fitnessstudio zur\u00fcck! Es gibt ein neues h\u00f6chstrichterliches Urteil gegen eine Fitnesskette.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.legalsmart.de\/blog\/naechstes-urteil-gegen-fitness-kette\/\" \/>\n<meta property=\"og:site_name\" content=\"LEGAL SMART Online Blog\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/guido.kluck\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-05T08:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Guido Kluck, LL.M.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/kluck\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guido Kluck, LL.M.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/naechstes-urteil-gegen-fitness-kette\/\",\"url\":\"https:\/\/www.legalsmart.de\/blog\/naechstes-urteil-gegen-fitness-kette\/\",\"name\":\"N\u00e4chstes Urteil gegen Fitness-Kette | LEGAL SMART Online Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#website\"},\"datePublished\":\"2022-10-05T08:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/0869c669bccbe2e56b149b214913b000\"},\"description\":\"Fordern Sie Ihre Beitr\u00e4ge f\u00fcr das Fitnessstudio zur\u00fcck! Es gibt ein neues h\u00f6chstrichterliches Urteil gegen eine Fitnesskette.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.legalsmart.de\/blog\/naechstes-urteil-gegen-fitness-kette\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.legalsmart.de\/blog\/naechstes-urteil-gegen-fitness-kette\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/naechstes-urteil-gegen-fitness-kette\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.legalsmart.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"N\u00e4chstes Urteil gegen Fitness-Kette\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#website\",\"url\":\"https:\/\/www.legalsmart.de\/blog\/\",\"name\":\"LEGAL SMART Online Blog\",\"description\":\"Die innovative Kanzlei\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.legalsmart.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/0869c669bccbe2e56b149b214913b000\",\"name\":\"Guido Kluck, LL.M.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.legalsmart.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-IMG_2698-e1535879860494-96x96.jpg\",\"contentUrl\":\"https:\/\/www.legalsmart.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-IMG_2698-e1535879860494-96x96.jpg\",\"caption\":\"Guido Kluck, LL.M.\"},\"description\":\"Rechtsanwalt Guido Kluck LL.M. ist Partner der Kanzlei LEGAL SMART am Standort Berlin. Er ist Ansprechpartner f\u00fcr das Recht der neuen Medien sowie f\u00fcr die Bereiche Wettbewerbsrecht, Markenrecht, Urheberrecht, IT-Recht, Vertragsrecht und das Datenschutzrecht (DSGVO).\",\"sameAs\":[\"https:\/\/legalsmart.de\/team_kluck.php\",\"https:\/\/www.facebook.com\/guido.kluck\",\"https:\/\/x.com\/https:\/\/twitter.com\/kluck\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"N\u00e4chstes Urteil gegen Fitness-Kette | LEGAL SMART Online Blog","description":"Fordern Sie Ihre Beitr\u00e4ge f\u00fcr das Fitnessstudio zur\u00fcck! Es gibt ein neues h\u00f6chstrichterliches Urteil gegen eine Fitnesskette.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.legalsmart.de\/blog\/naechstes-urteil-gegen-fitness-kette\/","og_locale":"de_DE","og_type":"article","og_title":"N\u00e4chstes Urteil gegen Fitness-Kette | LEGAL SMART Online Blog","og_description":"Fordern Sie Ihre Beitr\u00e4ge f\u00fcr das Fitnessstudio zur\u00fcck! Es gibt ein neues h\u00f6chstrichterliches Urteil gegen eine Fitnesskette.","og_url":"https:\/\/www.legalsmart.de\/blog\/naechstes-urteil-gegen-fitness-kette\/","og_site_name":"LEGAL SMART Online Blog","article_author":"https:\/\/www.facebook.com\/guido.kluck","article_published_time":"2022-10-05T08:00:00+00:00","author":"Guido Kluck, LL.M.","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/kluck","twitter_misc":{"Verfasst von":"Guido Kluck, LL.M.","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.legalsmart.de\/blog\/naechstes-urteil-gegen-fitness-kette\/","url":"https:\/\/www.legalsmart.de\/blog\/naechstes-urteil-gegen-fitness-kette\/","name":"N\u00e4chstes Urteil gegen Fitness-Kette | LEGAL SMART Online Blog","isPartOf":{"@id":"https:\/\/www.legalsmart.de\/blog\/#website"},"datePublished":"2022-10-05T08:00:00+00:00","author":{"@id":"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/0869c669bccbe2e56b149b214913b000"},"description":"Fordern Sie Ihre Beitr\u00e4ge f\u00fcr das Fitnessstudio zur\u00fcck! Es gibt ein neues h\u00f6chstrichterliches Urteil gegen eine Fitnesskette.","breadcrumb":{"@id":"https:\/\/www.legalsmart.de\/blog\/naechstes-urteil-gegen-fitness-kette\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.legalsmart.de\/blog\/naechstes-urteil-gegen-fitness-kette\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.legalsmart.de\/blog\/naechstes-urteil-gegen-fitness-kette\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.legalsmart.de\/blog\/"},{"@type":"ListItem","position":2,"name":"N\u00e4chstes Urteil gegen Fitness-Kette"}]},{"@type":"WebSite","@id":"https:\/\/www.legalsmart.de\/blog\/#website","url":"https:\/\/www.legalsmart.de\/blog\/","name":"LEGAL SMART Online Blog","description":"Die innovative Kanzlei","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.legalsmart.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/0869c669bccbe2e56b149b214913b000","name":"Guido Kluck, LL.M.","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.legalsmart.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-IMG_2698-e1535879860494-96x96.jpg","contentUrl":"https:\/\/www.legalsmart.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-IMG_2698-e1535879860494-96x96.jpg","caption":"Guido Kluck, LL.M."},"description":"Rechtsanwalt Guido Kluck LL.M. ist Partner der Kanzlei LEGAL SMART am Standort Berlin. Er ist Ansprechpartner f\u00fcr das Recht der neuen Medien sowie f\u00fcr die Bereiche Wettbewerbsrecht, Markenrecht, Urheberrecht, IT-Recht, Vertragsrecht und das Datenschutzrecht (DSGVO).","sameAs":["https:\/\/legalsmart.de\/team_kluck.php","https:\/\/www.facebook.com\/guido.kluck","https:\/\/x.com\/https:\/\/twitter.com\/kluck"]}]}},"_links":{"self":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/posts\/11277","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/comments?post=11277"}],"version-history":[{"count":1,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/posts\/11277\/revisions"}],"predecessor-version":[{"id":11278,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/posts\/11277\/revisions\/11278"}],"wp:attachment":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/media?parent=11277"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/categories?post=11277"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/tags?post=11277"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}