{"id":3700,"date":"2012-11-22T09:15:23","date_gmt":"2012-11-22T08:15:23","guid":{"rendered":"https:\/\/www.legalsmart.de\/blog\/?p=3700"},"modified":"2012-11-22T09:15:23","modified_gmt":"2012-11-22T08:15:23","slug":"zwangsvollstreckung-ab-1-januar-2013-eidesstattliche-versicherung-wird-vermogensauskunft","status":"publish","type":"post","link":"https:\/\/www.legalsmart.de\/blog\/zwangsvollstreckung-ab-1-januar-2013-eidesstattliche-versicherung-wird-vermogensauskunft\/","title":{"rendered":"Zwangsvollstreckung ab 1. Januar 2013 &#8211; eidesstattliche Versicherung wird Verm\u00f6gensauskunft"},"content":{"rendered":"<p>Das Verfahren zur Abgabe der eidesstattlichen Versicherung wird jedoch nicht nur in Verfahren zur Abgabe der Verm\u00f6gensauskunft umbenannt. Entscheidender Unterschied ist, dass die Abgabe der Verm\u00f6gensauskunft auch verlangt werden kann, ohne dass vorher ein fruchtloser Vollstreckungsversuch durch den Gerichtsvollzieher unternommen worden sein muss (<a href=\"https:\/\/dejure.org\/gesetze\/ZPO\/802c.html\" title=\"&sect; 802c ZPO: Verm&ouml;gensauskunft des Schuldners\">\u00a7 802c ZPO<\/a> n.F.). Gl\u00e4ubiger k\u00f6nnen sich also schon vor der eigentlichen Zwangsvollstreckung \u00fcber die pers\u00f6nlichen und wirtschaftlichen Verh\u00e4ltnisse des Schuldners informieren. Ob dies sinnvoll ist, muss im Einzelfall und insbesondere auch unter Kostengesichtspunkten entschieden werden. Denn die Kosten des Verfahrens werden sich erh\u00f6hen, und dies voraussichtlich zum 01.07.2013 noch einmal, und damit insgesamt deutlich.\u00a0Im schlimmsten Fall kommen einem andere Gl\u00e4ubiger mit ihren Vollstreckungsma\u00dfnahmen zuvor. Dem kann wie bisher durch den sog. kombinierten Vollstreckungsauftrag entgegengewirkt werden, bei dem der Gerichtsvollzieher nach nicht oder nur teilweise erfolgreicher Sachpf\u00e4ndung dem Schuldner sofort die Verm\u00f6gensauskunft abverlangt.<\/p>\n<p>An Umfang und Inhalt der Verm\u00f6gensauskunft \u00e4ndert sich nur insoweit etwas, als dass der Schuldner jetzt auch seinen Geburtsnamen, sein Geburtsdatum und den Geburtsort angeben muss, um Personenverwechslungen noch besser vermeiden zu k\u00f6nnen.<\/p>\n<p>Der Gerichtsvollzieher muss dem Schuldner vor der Abgabe der Verm\u00f6gensauskunft eine Zahlungsfrist von zwei Wochen setzten (<a href=\"https:\/\/dejure.org\/gesetze\/ZPO\/802f.html\" title=\"&sect; 802f ZPO: Abnahme der Verm&ouml;gensauskunft\">\u00a7 802f Abs. 1 S. 1 ZPO<\/a> n.F.). Gleichzeitig kann er den Termin zur Abgabe der Verm\u00f6gensauskunft festsetzten. Die Abnahme der Auskunft kann auch weiter in der Wohnung des Schuldners erfolgen (<a href=\"https:\/\/dejure.org\/gesetze\/ZPO\/802f.html\" title=\"&sect; 802f ZPO: Abnahme der Verm&ouml;gensauskunft\">\u00a7 802f Abs. 2 S. 1 ZPO<\/a> n.F.). Dem kann der Schuldner binnen einer Woche widersprechen. Vers\u00e4umt er die Frist und wird er zum Termin nicht angetroffen oder verweigert er die Auskunft, so kann auf Antrag des Gl\u00e4ubigers Haftbefehl gegen ihn ergehen.\u00a0Mit der Terminsladung hat der Gerichtsvollzieher den Schuldner \u00fcber seine Rechte und Pflichten im Verfahren, \u00fcber die Folgen von Pflichtverletzungen, \u00fcber die M\u00f6glichkeit der Einholung von Ausk\u00fcnften von Dritten sowie der Eintragung in das Schuldnerverzeichnis zu belehren (<a href=\"https:\/\/dejure.org\/gesetze\/ZPO\/802f.html\" title=\"&sect; 802f ZPO: Abnahme der Verm&ouml;gensauskunft\">\u00a7 802f Abs. 3 ZPO<\/a> n.F.).<\/p>\n<p>Das im Rahmen der Verm\u00f6gensauskunft zu erstellende Verm\u00f6gensverzeichnis wird von dem Gerichtsvollzieher nur noch als elektronisches Dokument errichtet (<a href=\"https:\/\/dejure.org\/gesetze\/ZPO\/802f.html\" title=\"&sect; 802f ZPO: Abnahme der Verm&ouml;gensauskunft\">\u00a7 802f Abs. 5 ZPO<\/a> n.F.), welches vom Gerichtsvollzieher beim zentralen Vollstreckungsgericht des jeweiligen Bundeslandes hinterlegt wird\u00a0(<a href=\"https:\/\/dejure.org\/gesetze\/ZPO\/802f.html\" title=\"&sect; 802f ZPO: Abnahme der Verm&ouml;gensauskunft\">\u00a7 802f Abs. 6 ZPO<\/a> n.F.). F\u00fcr Berlin ist das das Amtsgericht Mitte. Der Gl\u00e4ubiger erh\u00e4lt vom Gerichtsvollzieher einen Ausdruck des Verzeichnisses.<\/p>\n<p>Die erneute Abgabe der Verm\u00f6gensauskunft kann schon nach zwei Jahren verlangt werden (<a href=\"https:\/\/dejure.org\/gesetze\/ZPO\/802d.html\" title=\"&sect; 802d ZPO: Weitere Verm&ouml;gensauskunft\">\u00a7 802d Abs. 1 S. 1 ZPO<\/a> n.F.). Die Sperrfrist f\u00fcr die eidesstattliche Versicherung betrug drei Jahre. Schon vor Ablauf der zwei Jahre kann die erneute Abgabe der Verm\u00f6gensauskunft verlangt werden, wenn Tatsachen glaubhaft gemacht werden, die auf eine wesentliche Ver\u00e4nderung der Verm\u00f6gensverh\u00e4ltnisse des Schuldners schlie\u00dfen lassen. Durch diesen unbestimmten Rechtsbegriff wird der Ausnahmebereich gegen\u00fcber der bisherigen Regelung (sp\u00e4terer Verm\u00f6genserwerb oder Aufl\u00f6sung eines bisherigen Arbeitsverh\u00e4ltnisses) erheblich erweitert. Die Rechtsprechung wird im Laufe der Zeit f\u00fcr eine Konkretisierung diese unbestimmten Rechtsbegriffs sorgen.<\/p>\n<p>WK LEGAL ber\u00e4t Sie \u00a0insbesondere auch \u00fcber die Wirtschaftlichkeit der zwangsweisen Beitreibung Ihrer Forderungen und vertritt Sie zu angemessenen Konditionen in der Zwangsvollstreckung.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Verfahren zur Abgabe der eidesstattlichen Versicherung wird jedoch nicht nur in Verfahren zur Abgabe der Verm\u00f6gensauskunft umbenannt. Entscheidender Unterschied ist, dass die Abgabe der Verm\u00f6gensauskunft auch verlangt werden kann, ohne dass vorher ein fruchtloser Vollstreckungsversuch durch den Gerichtsvollzieher unternommen worden sein muss (\u00a7 802c ZPO n.F.). Gl\u00e4ubiger k\u00f6nnen sich also schon vor der eigentlichen [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40,41,43],"tags":[512,1325,1699,1782,1844,2155,2171,3013,3110,3177,3178,3285,3733,4008,4063,4075,4120,4128],"class_list":["post-3700","post","type-post","status-publish","format-standard","hentry","category-wirtschaftsrecht","category-zivilrecht","category-zwangsvollstreckung","tag-amtsgericht-mitte","tag-eidesstattliche-versicherung","tag-gerichtsvollzieher","tag-glaubiger","tag-haftbefehl","tag-kombiauftrag","tag-kosten","tag-reform-der-sachaufklarung","tag-sachpfandung","tag-schuldner","tag-schuldnerverzeichnis","tag-sperrfrist","tag-vermogensauskunft","tag-wohnung","tag-zahlungsfrist","tag-zentrale-vollstreckungsgerichte","tag-zwangsvollstreckung","tag-zwvollstrandg"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Januar 2013 - eidesstattliche Versicherung wird Verm\u00f6gensauskunft<\/title>\n<meta name=\"description\" content=\"Entscheidender Unterschied ist, dass die Verm\u00f6gensauskunft auch ohne vorherige fruchtlose Vollstreckung durch den Gerichtsvollzieher verlangt werden kann.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.legalsmart.de\/blog\/zwangsvollstreckung-ab-1-januar-2013-eidesstattliche-versicherung-wird-vermogensauskunft\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Januar 2013 - eidesstattliche Versicherung wird Verm\u00f6gensauskunft\" \/>\n<meta property=\"og:description\" content=\"Entscheidender Unterschied ist, dass die Verm\u00f6gensauskunft auch ohne vorherige fruchtlose Vollstreckung durch den Gerichtsvollzieher verlangt werden kann.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.legalsmart.de\/blog\/zwangsvollstreckung-ab-1-januar-2013-eidesstattliche-versicherung-wird-vermogensauskunft\/\" \/>\n<meta property=\"og:site_name\" content=\"LEGAL SMART Online Blog\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-22T08:15:23+00:00\" \/>\n<meta name=\"author\" content=\"Wolfgang N. Sokoll\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wolfgang N. Sokoll\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/zwangsvollstreckung-ab-1-januar-2013-eidesstattliche-versicherung-wird-vermogensauskunft\/\",\"url\":\"https:\/\/www.legalsmart.de\/blog\/zwangsvollstreckung-ab-1-januar-2013-eidesstattliche-versicherung-wird-vermogensauskunft\/\",\"name\":\"Januar 2013 - eidesstattliche Versicherung wird Verm\u00f6gensauskunft\",\"isPartOf\":{\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#website\"},\"datePublished\":\"2012-11-22T08:15:23+00:00\",\"author\":{\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/f44f83d9a06475ee3f6cfd9553344253\"},\"description\":\"Entscheidender Unterschied ist, dass die Verm\u00f6gensauskunft auch ohne vorherige fruchtlose Vollstreckung durch den Gerichtsvollzieher verlangt werden kann.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.legalsmart.de\/blog\/zwangsvollstreckung-ab-1-januar-2013-eidesstattliche-versicherung-wird-vermogensauskunft\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.legalsmart.de\/blog\/zwangsvollstreckung-ab-1-januar-2013-eidesstattliche-versicherung-wird-vermogensauskunft\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/zwangsvollstreckung-ab-1-januar-2013-eidesstattliche-versicherung-wird-vermogensauskunft\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.legalsmart.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zwangsvollstreckung ab 1. Januar 2013 &#8211; eidesstattliche Versicherung wird Verm\u00f6gensauskunft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#website\",\"url\":\"https:\/\/www.legalsmart.de\/blog\/\",\"name\":\"LEGAL SMART Online Blog\",\"description\":\"Die innovative Kanzlei\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.legalsmart.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/f44f83d9a06475ee3f6cfd9553344253\",\"name\":\"Wolfgang N. Sokoll\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/16f6bece927ba0e9b1bdd20969804b00ff01d6f51c5ea775bff40af6dff70c79?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/16f6bece927ba0e9b1bdd20969804b00ff01d6f51c5ea775bff40af6dff70c79?s=96&d=mm&r=g\",\"caption\":\"Wolfgang N. Sokoll\"},\"description\":\"Rechtsanwalt und Mediator Wolfgang N. Sokoll war bis Ende November 2016 bei WK LEGAL Ihr Ansprechpartner f\u00fcr das Arbeitsrecht, das Insolvenzrecht, das Versicherungsrecht, das Forderungsmanagement, die Zwangsvollstreckung und die au\u00dfergerichtliche Streitbeilegung insbesondere im Wege der Mediation. Seit dem erreichen Sie ihn in seiner Anwaltskanzlei in Berlin Charlottenburg in der Hardenbergstra\u00dfe 12 telefonisch unter 030 120857200, per Fax unter 030 120857209 und per E-Mail unter info@mediation-recht.net.\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Januar 2013 - eidesstattliche Versicherung wird Verm\u00f6gensauskunft","description":"Entscheidender Unterschied ist, dass die Verm\u00f6gensauskunft auch ohne vorherige fruchtlose Vollstreckung durch den Gerichtsvollzieher verlangt werden kann.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.legalsmart.de\/blog\/zwangsvollstreckung-ab-1-januar-2013-eidesstattliche-versicherung-wird-vermogensauskunft\/","og_locale":"de_DE","og_type":"article","og_title":"Januar 2013 - eidesstattliche Versicherung wird Verm\u00f6gensauskunft","og_description":"Entscheidender Unterschied ist, dass die Verm\u00f6gensauskunft auch ohne vorherige fruchtlose Vollstreckung durch den Gerichtsvollzieher verlangt werden kann.","og_url":"https:\/\/www.legalsmart.de\/blog\/zwangsvollstreckung-ab-1-januar-2013-eidesstattliche-versicherung-wird-vermogensauskunft\/","og_site_name":"LEGAL SMART Online Blog","article_published_time":"2012-11-22T08:15:23+00:00","author":"Wolfgang N. Sokoll","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Wolfgang N. Sokoll","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.legalsmart.de\/blog\/zwangsvollstreckung-ab-1-januar-2013-eidesstattliche-versicherung-wird-vermogensauskunft\/","url":"https:\/\/www.legalsmart.de\/blog\/zwangsvollstreckung-ab-1-januar-2013-eidesstattliche-versicherung-wird-vermogensauskunft\/","name":"Januar 2013 - eidesstattliche Versicherung wird Verm\u00f6gensauskunft","isPartOf":{"@id":"https:\/\/www.legalsmart.de\/blog\/#website"},"datePublished":"2012-11-22T08:15:23+00:00","author":{"@id":"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/f44f83d9a06475ee3f6cfd9553344253"},"description":"Entscheidender Unterschied ist, dass die Verm\u00f6gensauskunft auch ohne vorherige fruchtlose Vollstreckung durch den Gerichtsvollzieher verlangt werden kann.","breadcrumb":{"@id":"https:\/\/www.legalsmart.de\/blog\/zwangsvollstreckung-ab-1-januar-2013-eidesstattliche-versicherung-wird-vermogensauskunft\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.legalsmart.de\/blog\/zwangsvollstreckung-ab-1-januar-2013-eidesstattliche-versicherung-wird-vermogensauskunft\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.legalsmart.de\/blog\/zwangsvollstreckung-ab-1-januar-2013-eidesstattliche-versicherung-wird-vermogensauskunft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.legalsmart.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Zwangsvollstreckung ab 1. Januar 2013 &#8211; eidesstattliche Versicherung wird Verm\u00f6gensauskunft"}]},{"@type":"WebSite","@id":"https:\/\/www.legalsmart.de\/blog\/#website","url":"https:\/\/www.legalsmart.de\/blog\/","name":"LEGAL SMART Online Blog","description":"Die innovative Kanzlei","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.legalsmart.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/f44f83d9a06475ee3f6cfd9553344253","name":"Wolfgang N. Sokoll","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/16f6bece927ba0e9b1bdd20969804b00ff01d6f51c5ea775bff40af6dff70c79?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/16f6bece927ba0e9b1bdd20969804b00ff01d6f51c5ea775bff40af6dff70c79?s=96&d=mm&r=g","caption":"Wolfgang N. Sokoll"},"description":"Rechtsanwalt und Mediator Wolfgang N. Sokoll war bis Ende November 2016 bei WK LEGAL Ihr Ansprechpartner f\u00fcr das Arbeitsrecht, das Insolvenzrecht, das Versicherungsrecht, das Forderungsmanagement, die Zwangsvollstreckung und die au\u00dfergerichtliche Streitbeilegung insbesondere im Wege der Mediation. Seit dem erreichen Sie ihn in seiner Anwaltskanzlei in Berlin Charlottenburg in der Hardenbergstra\u00dfe 12 telefonisch unter 030 120857200, per Fax unter 030 120857209 und per E-Mail unter info@mediation-recht.net."}]}},"_links":{"self":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/posts\/3700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/comments?post=3700"}],"version-history":[{"count":0,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/posts\/3700\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/media?parent=3700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/categories?post=3700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/tags?post=3700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}