{"id":3943,"date":"2012-12-31T00:13:04","date_gmt":"2012-12-30T23:13:04","guid":{"rendered":"https:\/\/www.legalsmart.de\/blog\/?p=3943"},"modified":"2012-12-31T00:13:04","modified_gmt":"2012-12-30T23:13:04","slug":"bgh-rechtsprechung-zum-keyword-advertising-google-adwords-bestatigt-und-prazisiert","status":"publish","type":"post","link":"https:\/\/www.legalsmart.de\/blog\/bgh-rechtsprechung-zum-keyword-advertising-google-adwords-bestatigt-und-prazisiert\/","title":{"rendered":"BGH: Rechtsprechung zum Keyword-Advertising (Google AdWords) best\u00e4tigt und pr\u00e4zisiert"},"content":{"rendered":"<p>BGH\u00a0Pressemitteilung Nr. 211\/2012<\/p>\n<p>\u201cDer unter anderem f\u00fcr das Markenrecht zust\u00e4ndige I. Zivilsenat des Bundesgerichtshofs hat seine Rechtsprechung zur Zul\u00e4ssigkeit des Keyword-Advertising, bei dem Internetnutzern anhand eines mit der Marke identischen oder verwechselbaren Schl\u00fcsselworts die Werbung eines Dritten angezeigt wird, best\u00e4tigt und pr\u00e4zisiert.<\/p>\n<p>&nbsp;<\/p>\n<p>Die Kl\u00e4gerin ist Inhaberin der ausschlie\u00dflichen Lizenz an der unter anderem f\u00fcr Pralinen und Schokolade eingetragenen deutschen Marke \u201cMOST\u201d. Sie betreibt unter der Internetadresse \u201cwww.most-shop.com\u201d einen \u201cMOST-Shop\u201d, \u00fcber den sie hochwertige Konfiserie- und Schokoladenprodukte vertreibt. Die Beklagte unterh\u00e4lt unter den Internetadressen \u201cwww.feinkost-geschenke.de\u201d und \u201cwww.selection-exquisit.de\u201d einen Onlineshop f\u00fcr Geschenke, Pralinen und Schokolade. Sie schaltete im Januar 2007 bei der Suchmaschine Google eine Adwords-Anzeige f\u00fcr ihren Internetshop. Als Schl\u00fcsselwort (\u201dKeyword\u201d), dessen Eingabe in die Suchmaske das Erscheinen der Anzeige ausl\u00f6sen sollte, hatte die Beklagte den Begriff \u201cPralinen\u201d mit der Option \u201cweitgehend passende Keywords\u201d gew\u00e4hlt. In der Liste der \u201cweitgehend passenden Keywords\u201d stand auch das Schl\u00fcsselwort \u201cmost pralinen\u201d. Gab ein Nutzer den Suchbegriff \u201cMOST Pralinen\u201d ein, erschien rechts neben den Suchergebnissen (auf vier Zeilen verteilt) folgende Anzeige der Beklagten: \u201cPralinen\/Weine, Pralinen, Feinkost, Pr\u00e4sente\/Genie\u00dfen und schenken!\/www.feinkost-geschenke.de.\u201d \u00dcber den in der Anzeige angegebenen Link \u201cwww.feinkost-geschenke.de\u201d gelangte der Suchmaschinennutzer auf die Homepage der Beklagten unter der Internetadresse \u201cwww.selection-exquisit.de\u201d. In dem Onlineshop der Beklagten wurden keine Produkte mit dem Zeichen \u201cMOST\u201d vertrieben.<\/p>\n<p>&nbsp;<\/p>\n<p>Die Kl\u00e4gerin ist der Ansicht, die Beklagte habe durch die Schaltung der Anzeige das Recht an der Marke \u201cMOST\u201d verletzt. Sie hat die Beklagte unter anderem auf Unterlassung in Anspruch genommen. Das Landgericht hat der Klage stattgegeben. Die Berufung der Beklagten ist ohne Erfolg geblieben. Der Bundesgerichtshof hat das Berufungsurteil aufgehoben und die Klage abgewiesen.<\/p>\n<p>&nbsp;<\/p>\n<p>Der Bundesgerichtshof hat seine Rechtsprechung (BGH, Urteil vom 13. Januar 2011 &#8211;\u00a0<a title=\"I ZR 125\/07 (2 zugeordnete Entscheidungen)\" href=\"http:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=I%20ZR%20125\/07\" target=\"_blank\">I ZR 125\/07<\/a>,\u00a0<a title=\"BGH, 13.01.2011 - I ZR 125\/07: Wettbewerbsrecht - Nutzung eines Markenzeichens f\u00fcr Internetwerb...\" href=\"http:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=GRUR%202011,%20828\" target=\"_blank\">GRUR 2011, 828<\/a>\u00a0&#8211; Bananabay II; Urteil vom 13. Januar 2011 &#8211;\u00a0<a title=\"BGH, 13.01.2011 - I ZR 46\/08: Wettbewerbsrecht - Schalten einer verwechselbaren Google-Werbeanz...\" href=\"http:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=I%20ZR%2046\/08\" target=\"_blank\">I ZR 46\/08<\/a>,\u00a0<a title=\"BGH, 13.01.2011 - I ZR 46\/08: Wettbewerbsrecht - Schalten einer verwechselbaren Google-Werbeanz...\" href=\"http:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=MMR%202011,%20608\" target=\"_blank\">MMR 2011, 608<\/a>) best\u00e4tigt, nach der beim \u201cKeyword-Advertising\u201d eine Markenverletzung unter dem Gesichtspunkt der Beeintr\u00e4chtigung der Herkunftsfunktion der Marke grunds\u00e4tzlich ausgeschlossen ist, wenn die Werbung &#8211; wie im Streitfall &#8211; in einem von der Trefferliste eindeutig getrennten und entsprechend gekennzeichneten Werbeblock erscheint und selbst weder die Marke noch sonst einen Hinweis auf den Markeninhaber oder die unter der Marke angebotenen Produkte enth\u00e4lt. Der BGH hat klargestellt, dass dies auch dann gilt, wenn die Anzeige nicht auf das Fehlen einer wirtschaftlichen Verbindung zwischen dem Werbenden und dem Markeninhaber hinweist und dass allein der Umstand, dass in der Anzeige Produkte der unter der Marke angebotenen Art mit Gattungsbegriffen bezeichnet werden (im Streitfall \u201cPralinen\u201d usw.), nicht zu einer Beeintr\u00e4chtigung der Herkunftsfunktion der Marke f\u00fchrt. Diese Beurteilung steht &#8211; so der BGH &#8211; in Einklang mit der Rechtsprechung des EuGH (zuletzt EuGH, Urteil vom 22. September 2011 &#8211;\u00a0<a title=\"C-323\/09 (2 zugeordnete Entscheidungen)\" href=\"http:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=C-323\/09\" target=\"_blank\">C-323\/09<\/a>,\u00a0<a title=\"EuGH, 22.09.2011 - C-323\/09: Interflora Inc. und Interflora British Unit gegen Marks &amp; Spencer ...\" href=\"http:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=GRUR%202011,%201124\" target=\"_blank\">GRUR 2011, 1124<\/a>\u00a0&#8211; Interflora\/M&amp;S Interflora Inc.). Danach ist es Sache des nationalen Gerichts, die Frage der Beeintr\u00e4chtigung der Herkunftsfunktion anhand der vom Gerichtshof entwickelten Ma\u00dfst\u00e4be unter Ber\u00fccksichtigung aller Faktoren, die es f\u00fcr relevant erachtet, zu pr\u00fcfen. Der BGH hat deshalb auch im Blick auf die Rechtsprechung des \u00f6sterreichischen Obersten Gerichtshofs (GRUR Int. 2011, 173, 175 &#8211; BergSpechte II) und der franz\u00f6sischen Cour de cassation (<a href=\"https:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=GRUR%20Int.%202011,%20625\" title=\"BGH, 01.03.2011 - X ZR 72\/08: Kosmetisches Sonnenschutzmittel III\">GRUR Int. 2011, 625<\/a> &#8211; CNRRH), die bei der Beurteilung von Adwords-Anzeigen unter Ber\u00fccksichtigung der von ihnen als relevant erachteten Faktoren zu anderen Ergebnissen gelangt sind, keine Vorlage an den EuGH f\u00fcr geboten erachtet.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Vorinstanzen:<\/strong><br \/>OLG Braunschweig, Urteil vom 24.11.2010, Az.\u00a0<a title=\"2 U 113\/08 (3 zugeordnete Entscheidungen)\" href=\"http:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=2%20U%20113\/08\" target=\"_blank\">2 U 113\/08<\/a>,\u00a0<a title=\"GRUR-RR 2011, 91 (3 zugeordnete Entscheidungen)\" href=\"http:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=GRUR-RR%202011,%2091\" target=\"_blank\">GRUR-RR 2011, 91<\/a><br \/>LG Braunschweig, Urteil vom 27.08.2008, Az. <a href=\"https:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=9%20O%201263\/07\" title=\"9 O 1263\/07 (2 zugeordnete Entscheidungen)\">9 O 1263\/07<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BGH\u00a0Pressemitteilung Nr. 211\/2012 \u201cDer unter anderem f\u00fcr das Markenrecht zust\u00e4ndige I. Zivilsenat des Bundesgerichtshofs hat seine Rechtsprechung zur Zul\u00e4ssigkeit des Keyword-Advertising, bei dem Internetnutzern anhand eines mit der Marke identischen oder verwechselbaren Schl\u00fcsselworts die Werbung eines Dritten angezeigt wird, best\u00e4tigt und pr\u00e4zisiert. &nbsp; Die Kl\u00e4gerin ist Inhaberin der ausschlie\u00dflichen Lizenz an der unter anderem f\u00fcr [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,31],"tags":[446,447,589,810,988,1090,1794,2131,2562,3152,3640],"class_list":["post-3943","post","type-post","status-publish","format-standard","hentry","category-markenrecht","category-urteile","tag-advertising","tag-adword","tag-anzeige","tag-az-i-zr-21710","tag-bgh","tag-bundesgerichtshof","tag-google","tag-keyword","tag-most-pralinen","tag-schlusselwort","tag-urteil-vom-13-12-2012"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BGH: Rechtsprechung zum Keyword-Advertising (Google AdWords) best\u00e4tigt und pr\u00e4zisiert<\/title>\n<meta name=\"description\" content=\"BGH: Rechtsprechung zum Keyword-Advertising (Google AdWords) best\u00e4tigt und pr\u00e4zisiert\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.legalsmart.de\/blog\/bgh-rechtsprechung-zum-keyword-advertising-google-adwords-bestatigt-und-prazisiert\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BGH: Rechtsprechung zum Keyword-Advertising (Google AdWords) best\u00e4tigt und pr\u00e4zisiert\" \/>\n<meta property=\"og:description\" content=\"BGH: Rechtsprechung zum Keyword-Advertising (Google AdWords) best\u00e4tigt und pr\u00e4zisiert\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.legalsmart.de\/blog\/bgh-rechtsprechung-zum-keyword-advertising-google-adwords-bestatigt-und-prazisiert\/\" \/>\n<meta property=\"og:site_name\" content=\"LEGAL SMART Online Blog\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/guido.kluck\" \/>\n<meta property=\"article:published_time\" content=\"2012-12-30T23:13:04+00:00\" \/>\n<meta name=\"author\" content=\"Guido Kluck, LL.M.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/kluck\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guido Kluck, LL.M.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/bgh-rechtsprechung-zum-keyword-advertising-google-adwords-bestatigt-und-prazisiert\/\",\"url\":\"https:\/\/www.legalsmart.de\/blog\/bgh-rechtsprechung-zum-keyword-advertising-google-adwords-bestatigt-und-prazisiert\/\",\"name\":\"BGH: Rechtsprechung zum Keyword-Advertising (Google AdWords) best\u00e4tigt und pr\u00e4zisiert\",\"isPartOf\":{\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#website\"},\"datePublished\":\"2012-12-30T23:13:04+00:00\",\"author\":{\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/0869c669bccbe2e56b149b214913b000\"},\"description\":\"BGH: Rechtsprechung zum Keyword-Advertising (Google AdWords) best\u00e4tigt und pr\u00e4zisiert\",\"breadcrumb\":{\"@id\":\"https:\/\/www.legalsmart.de\/blog\/bgh-rechtsprechung-zum-keyword-advertising-google-adwords-bestatigt-und-prazisiert\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.legalsmart.de\/blog\/bgh-rechtsprechung-zum-keyword-advertising-google-adwords-bestatigt-und-prazisiert\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/bgh-rechtsprechung-zum-keyword-advertising-google-adwords-bestatigt-und-prazisiert\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.legalsmart.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BGH: Rechtsprechung zum Keyword-Advertising (Google AdWords) best\u00e4tigt und pr\u00e4zisiert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#website\",\"url\":\"https:\/\/www.legalsmart.de\/blog\/\",\"name\":\"LEGAL SMART Online Blog\",\"description\":\"Die innovative Kanzlei\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.legalsmart.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/0869c669bccbe2e56b149b214913b000\",\"name\":\"Guido Kluck, LL.M.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.legalsmart.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-IMG_2698-e1535879860494-96x96.jpg\",\"contentUrl\":\"https:\/\/www.legalsmart.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-IMG_2698-e1535879860494-96x96.jpg\",\"caption\":\"Guido Kluck, LL.M.\"},\"description\":\"Rechtsanwalt Guido Kluck LL.M. ist Partner der Kanzlei LEGAL SMART am Standort Berlin. Er ist Ansprechpartner f\u00fcr das Recht der neuen Medien sowie f\u00fcr die Bereiche Wettbewerbsrecht, Markenrecht, Urheberrecht, IT-Recht, Vertragsrecht und das Datenschutzrecht (DSGVO).\",\"sameAs\":[\"https:\/\/legalsmart.de\/team_kluck.php\",\"https:\/\/www.facebook.com\/guido.kluck\",\"https:\/\/x.com\/https:\/\/twitter.com\/kluck\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BGH: Rechtsprechung zum Keyword-Advertising (Google AdWords) best\u00e4tigt und pr\u00e4zisiert","description":"BGH: Rechtsprechung zum Keyword-Advertising (Google AdWords) best\u00e4tigt und pr\u00e4zisiert","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.legalsmart.de\/blog\/bgh-rechtsprechung-zum-keyword-advertising-google-adwords-bestatigt-und-prazisiert\/","og_locale":"de_DE","og_type":"article","og_title":"BGH: Rechtsprechung zum Keyword-Advertising (Google AdWords) best\u00e4tigt und pr\u00e4zisiert","og_description":"BGH: Rechtsprechung zum Keyword-Advertising (Google AdWords) best\u00e4tigt und pr\u00e4zisiert","og_url":"https:\/\/www.legalsmart.de\/blog\/bgh-rechtsprechung-zum-keyword-advertising-google-adwords-bestatigt-und-prazisiert\/","og_site_name":"LEGAL SMART Online Blog","article_author":"https:\/\/www.facebook.com\/guido.kluck","article_published_time":"2012-12-30T23:13:04+00:00","author":"Guido Kluck, LL.M.","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/kluck","twitter_misc":{"Verfasst von":"Guido Kluck, LL.M.","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.legalsmart.de\/blog\/bgh-rechtsprechung-zum-keyword-advertising-google-adwords-bestatigt-und-prazisiert\/","url":"https:\/\/www.legalsmart.de\/blog\/bgh-rechtsprechung-zum-keyword-advertising-google-adwords-bestatigt-und-prazisiert\/","name":"BGH: Rechtsprechung zum Keyword-Advertising (Google AdWords) best\u00e4tigt und pr\u00e4zisiert","isPartOf":{"@id":"https:\/\/www.legalsmart.de\/blog\/#website"},"datePublished":"2012-12-30T23:13:04+00:00","author":{"@id":"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/0869c669bccbe2e56b149b214913b000"},"description":"BGH: Rechtsprechung zum Keyword-Advertising (Google AdWords) best\u00e4tigt und pr\u00e4zisiert","breadcrumb":{"@id":"https:\/\/www.legalsmart.de\/blog\/bgh-rechtsprechung-zum-keyword-advertising-google-adwords-bestatigt-und-prazisiert\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.legalsmart.de\/blog\/bgh-rechtsprechung-zum-keyword-advertising-google-adwords-bestatigt-und-prazisiert\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.legalsmart.de\/blog\/bgh-rechtsprechung-zum-keyword-advertising-google-adwords-bestatigt-und-prazisiert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.legalsmart.de\/blog\/"},{"@type":"ListItem","position":2,"name":"BGH: Rechtsprechung zum Keyword-Advertising (Google AdWords) best\u00e4tigt und pr\u00e4zisiert"}]},{"@type":"WebSite","@id":"https:\/\/www.legalsmart.de\/blog\/#website","url":"https:\/\/www.legalsmart.de\/blog\/","name":"LEGAL SMART Online Blog","description":"Die innovative Kanzlei","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.legalsmart.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/0869c669bccbe2e56b149b214913b000","name":"Guido Kluck, LL.M.","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.legalsmart.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-IMG_2698-e1535879860494-96x96.jpg","contentUrl":"https:\/\/www.legalsmart.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-IMG_2698-e1535879860494-96x96.jpg","caption":"Guido Kluck, LL.M."},"description":"Rechtsanwalt Guido Kluck LL.M. ist Partner der Kanzlei LEGAL SMART am Standort Berlin. Er ist Ansprechpartner f\u00fcr das Recht der neuen Medien sowie f\u00fcr die Bereiche Wettbewerbsrecht, Markenrecht, Urheberrecht, IT-Recht, Vertragsrecht und das Datenschutzrecht (DSGVO).","sameAs":["https:\/\/legalsmart.de\/team_kluck.php","https:\/\/www.facebook.com\/guido.kluck","https:\/\/x.com\/https:\/\/twitter.com\/kluck"]}]}},"_links":{"self":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/posts\/3943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/comments?post=3943"}],"version-history":[{"count":0,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/posts\/3943\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/media?parent=3943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/categories?post=3943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/tags?post=3943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}