{"id":4064,"date":"2013-01-11T11:32:23","date_gmt":"2013-01-11T10:32:23","guid":{"rendered":"https:\/\/www.legalsmart.de\/blog\/?p=4064"},"modified":"2013-01-11T11:32:23","modified_gmt":"2013-01-11T10:32:23","slug":"mietkaution-und-abzug-neu-fur-alt","status":"publish","type":"post","link":"https:\/\/www.legalsmart.de\/blog\/mietkaution-und-abzug-neu-fur-alt\/","title":{"rendered":"Mietkaution und Abzug \u201eNeu f\u00fcr Alt\u201c"},"content":{"rendered":"<p style=\"text-align: justify\">Nicht selten ist nach dem Auszug eines Mieters die Kautionsr\u00fcckzahlung ein hei\u00dfes Eisen.<\/p>\n<p style=\"text-align: justify\">Ob und in welcher H\u00f6he die Mietsicherheit zur\u00fcckgezahlt werden muss, h\u00e4ngt nicht zuletzt davon ab, ob Besch\u00e4digungen an der Mietsache oder mitvermieteten Sachen durch den Vermieter geltend gemacht werden.\u00a0<\/p>\n<p style=\"text-align: justify\">Wenn demnach Sch\u00e4den verursacht wurden, wird der Vermieter den ehemaligen Mieter auffordern, die Sch\u00e4den zu beseitigen oder im Falle erfolgloser Fristsetzung selbst eine Schadensbeseitigung veranlassen. Die Kosten werden dann normalerweise mit der Mietsicherheit verrechnet. Daf\u00fcr ist sie schlie\u00dflich auch vorgesehen. Das gilt aber nur dann, wenn die Sch\u00e4den tats\u00e4chlich zu Lasten des Mieters gehen. Die Frage der Verursachung sollte vor der Schadensbeseitigung gekl\u00e4rt sein.<\/p>\n<p style=\"text-align: justify\">Steht fest, dass der Mieter beispielsweise den Einbauherd oder die Dusche besch\u00e4digt hat, so kann der Vermieter die Reparaturkosten oder die Neuanschaffung verlangen beziehungsweise durch die Kautionszahlung seine Ausgaben decken. Es handelt sich also um eine gew\u00f6hnliche Einstandspflicht f\u00fcr verursachte Sch\u00e4den. Zu beachten sind durch den Vermieter \u2013 wie auch in anderen F\u00e4llen \u2013 aber die Schadensminderungspflicht des <a href=\"https:\/\/dejure.org\/gesetze\/BGB\/254.html\" title=\"&sect; 254 BGB: Mitverschulden\">\u00a7 254 BGB<\/a> und die Vorteilsausgleichung. Vorsicht ist also schon dann geboten, wenn die Reparatur die Neuanschaffung wesentlich \u00fcbersteigt.<\/p>\n<p style=\"text-align: justify\">Grunds\u00e4tzlich gilt, dass der Gesch\u00e4digte durch die Ersatzleistung des Sch\u00e4digers nicht \u00e4rmer, aber auch nicht reicher gemacht werden soll, als er vor dem sch\u00e4digenden Ereignis gewesen ist (BGH, Urteil vom 13. M\u00e4rz 1990 \u2013 <a href=\"https:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=X%20ZR%2012\/89\" title=\"BGH, 13.03.1990 - X ZR 12\/89: Schadensersatz und Vorteilsausgleich bei Wartungsarbeiten\">X ZR 12\/89<\/a>). Hier ist jedoch anzumerken, dass ein Ausgleich nicht immer geboten ist, sondern nur, wenn eine Anrechnung der Vorteile f\u00fcr den Gesch\u00e4digten zumutbar ist und nicht gegen allgemeine rechtliche Wertungen verst\u00f6\u00dft.<\/p>\n<p style=\"text-align: justify\">War der mitvermietete Gegenstand am Anfang des Mietverh\u00e4ltnisses nicht neu, ist die Gesamtnutzungsdauer bei der Schadensberechnung normalerweise zugrunde zu legen.<\/p>\n<p style=\"text-align: justify\">Sinn der Vorteilsausgleichung ist es, einen Ausgleich f\u00fcr eine Verl\u00e4ngerung der Gebrauchsm\u00f6glichkeit der Sache bei Neuanschaffung zu bieten. Wird ein 5 Jahre alter Herd, der eine generelle Lebensdauer von 15 Jahren aufweisen w\u00fcrde, kaputt durch den Mieter zur\u00fcckgegeben, so kann der Vermieter theoretisch bei Neukauf wieder 15 Jahre den neuen Herd nutzen. Er w\u00e4re also um 5 Jahre Nutzung bereichert. Hier f\u00e4llt dann auch das Stichwort wirtschaftliche Besserstellung. Um eine solche grunds\u00e4tzlich zu unterbinden, kann bei einem berechtigten Abzug \u201eneu f\u00fcr alt\u201c der Vermieter in derartigen F\u00e4llen eben nur 2\/3 des markt\u00fcblichen Neuanschaffungspreises verlangen. Im Beispiel w\u00e4ren es also EUR 666,66 bei einem Neupreis von EUR 999,99 f\u00fcr den Herd.<\/p>\n<p style=\"text-align: justify\">Der Vermieter ist also gut beraten, wenn er bei besch\u00e4digten Mietgegenst\u00e4nden in Erfahrung bringt, wie hoch der Marktpreis der Sache ist und einen gerechten Abzug \u00a0\u201eneu f\u00fcr alt\u201c vornimmt. Dann ist er grunds\u00e4tzlich nicht dem Einwand des \u00fcberh\u00f6hten Einbehalts der Kaution ausgesetzt. Zu beachten ist noch, dass in der Rechtsprechung f\u00fcr bestimmte Gegenst\u00e4nde vertreten wird, diese unterl\u00e4gen keinem Wertverlust durch Alterung, weshalb die Vorteilsausgleichung nicht zum Zuge komme.<\/p>\n<p>WK LEGAL ber\u00e4t und vertritt sowohl Privatpersonen als auch Unternehmen in s\u00e4mtlichen Fragen des Grundst\u00fccks- und Mietrechts. Wenn Sie mehr erfahren wollen, schreiben Sie uns eine E-Mail an info@wklegal.de<\/p>\n<p>Sie haben zu diesem Artikel weitergehende Fragen? Stellen Sie Ihre Fragen direkt und unverbindlich an den Autor dieses Artikels \u00fcber das nachfolgende Kontaktformular.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nicht selten ist nach dem Auszug eines Mieters die Kautionsr\u00fcckzahlung ein hei\u00dfes Eisen. Ob und in welcher H\u00f6he die Mietsicherheit zur\u00fcckgezahlt werden muss, h\u00e4ngt nicht zuletzt davon ab, ob Besch\u00e4digungen an der Mietsache oder mitvermieteten Sachen durch den Vermieter geltend gemacht werden.\u00a0 Wenn demnach Sch\u00e4den verursacht wurden, wird der Vermieter den ehemaligen Mieter auffordern, die [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,23,33,36,40,41],"tags":[47,71,434,567,1004,1433,1654,1704,1706,1909,2120,2289,2434,2484,2487,2502,2506,2650,2651,3040,3126,3724,3889,3891,3954,3987],"class_list":["post-4064","post","type-post","status-publish","format-standard","hentry","category-allgemeines","category-mietrecht","category-versicherungsrecht","category-weg-recht","category-wirtschaftsrecht","category-zivilrecht","tag-neu-fur-alt","tag--254-bgb","tag-abzug","tag-anrechnung","tag-bgh-urteil-vom-13-marz-1990-x-zr-1289","tag-ersatzleistung","tag-gebrauchsmoglichkeit","tag-gesamtnutzungsdauer","tag-geschadigter","tag-herd","tag-kaution","tag-lebensdauer","tag-marktpreis","tag-mieters","tag-mietgegenstande","tag-mietsicherheit","tag-mietverhaltnis","tag-neuanschaffung","tag-neuanschaffungspreis","tag-reparatur","tag-schadensberechnung","tag-vermieter","tag-vorteile","tag-vorteilsausgleichung","tag-wertverlust","tag-wirtschaftliche-besserstellung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mietkaution und Abzug \u201eNeu f\u00fcr Alt\u201c<\/title>\n<meta name=\"description\" content=\"Der Artikel besch\u00e4ftigt sich mit den Schadensberechnungsproblemen bei Besch\u00e4digung von Mietsachen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.legalsmart.de\/blog\/mietkaution-und-abzug-neu-fur-alt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mietkaution und Abzug \u201eNeu f\u00fcr Alt\u201c\" \/>\n<meta property=\"og:description\" content=\"Der Artikel besch\u00e4ftigt sich mit den Schadensberechnungsproblemen bei Besch\u00e4digung von Mietsachen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.legalsmart.de\/blog\/mietkaution-und-abzug-neu-fur-alt\/\" \/>\n<meta property=\"og:site_name\" content=\"LEGAL SMART Online Blog\" \/>\n<meta property=\"article:published_time\" content=\"2013-01-11T10:32:23+00:00\" \/>\n<meta name=\"author\" content=\"Hagen Zeitz, LL.M.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hagen Zeitz, LL.M.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/mietkaution-und-abzug-neu-fur-alt\/\",\"url\":\"https:\/\/www.legalsmart.de\/blog\/mietkaution-und-abzug-neu-fur-alt\/\",\"name\":\"Mietkaution und Abzug \u201eNeu f\u00fcr Alt\u201c\",\"isPartOf\":{\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#website\"},\"datePublished\":\"2013-01-11T10:32:23+00:00\",\"author\":{\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/d1184d836263690a1bb38d916033d0c6\"},\"description\":\"Der Artikel besch\u00e4ftigt sich mit den Schadensberechnungsproblemen bei Besch\u00e4digung von Mietsachen.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.legalsmart.de\/blog\/mietkaution-und-abzug-neu-fur-alt\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.legalsmart.de\/blog\/mietkaution-und-abzug-neu-fur-alt\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/mietkaution-und-abzug-neu-fur-alt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.legalsmart.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mietkaution und Abzug \u201eNeu f\u00fcr Alt\u201c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#website\",\"url\":\"https:\/\/www.legalsmart.de\/blog\/\",\"name\":\"LEGAL SMART Online Blog\",\"description\":\"Die innovative Kanzlei\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.legalsmart.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/d1184d836263690a1bb38d916033d0c6\",\"name\":\"Hagen Zeitz, LL.M.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5e6d25234c44b957b67b29d927a01106baae5175005cc8f165a565e625c21ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5e6d25234c44b957b67b29d927a01106baae5175005cc8f165a565e625c21ca?s=96&d=mm&r=g\",\"caption\":\"Hagen Zeitz, LL.M.\"},\"description\":\"Rechtsanwalt Hagen Zeitz, LL.M. ist Ansprechpartner f\u00fcr die Bereiche Immobilienrecht, Zwangsvollstreckungsrecht, Gesellschaftsrecht und das allgemeine Zivilrecht. Zu seinen T\u00e4tigkeitsschwerpunkten geh\u00f6rt ferner die Beratung von spanischsprachigen Mandanten in Deutschland, sowie die Unterst\u00fctzung von Mandanten im deutsch-spanischen Rechtsverkehr. Zu seinen Mandanten z\u00e4hlen nationale und internationale KMU\u00b4s, sowie Privatpersonen.\",\"sameAs\":[\"http:\/\/www.wklegal.de\/ansprechpartner\/zeitz.php\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mietkaution und Abzug \u201eNeu f\u00fcr Alt\u201c","description":"Der Artikel besch\u00e4ftigt sich mit den Schadensberechnungsproblemen bei Besch\u00e4digung von Mietsachen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.legalsmart.de\/blog\/mietkaution-und-abzug-neu-fur-alt\/","og_locale":"de_DE","og_type":"article","og_title":"Mietkaution und Abzug \u201eNeu f\u00fcr Alt\u201c","og_description":"Der Artikel besch\u00e4ftigt sich mit den Schadensberechnungsproblemen bei Besch\u00e4digung von Mietsachen.","og_url":"https:\/\/www.legalsmart.de\/blog\/mietkaution-und-abzug-neu-fur-alt\/","og_site_name":"LEGAL SMART Online Blog","article_published_time":"2013-01-11T10:32:23+00:00","author":"Hagen Zeitz, LL.M.","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Hagen Zeitz, LL.M.","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.legalsmart.de\/blog\/mietkaution-und-abzug-neu-fur-alt\/","url":"https:\/\/www.legalsmart.de\/blog\/mietkaution-und-abzug-neu-fur-alt\/","name":"Mietkaution und Abzug \u201eNeu f\u00fcr Alt\u201c","isPartOf":{"@id":"https:\/\/www.legalsmart.de\/blog\/#website"},"datePublished":"2013-01-11T10:32:23+00:00","author":{"@id":"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/d1184d836263690a1bb38d916033d0c6"},"description":"Der Artikel besch\u00e4ftigt sich mit den Schadensberechnungsproblemen bei Besch\u00e4digung von Mietsachen.","breadcrumb":{"@id":"https:\/\/www.legalsmart.de\/blog\/mietkaution-und-abzug-neu-fur-alt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.legalsmart.de\/blog\/mietkaution-und-abzug-neu-fur-alt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.legalsmart.de\/blog\/mietkaution-und-abzug-neu-fur-alt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.legalsmart.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Mietkaution und Abzug \u201eNeu f\u00fcr Alt\u201c"}]},{"@type":"WebSite","@id":"https:\/\/www.legalsmart.de\/blog\/#website","url":"https:\/\/www.legalsmart.de\/blog\/","name":"LEGAL SMART Online Blog","description":"Die innovative Kanzlei","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.legalsmart.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/d1184d836263690a1bb38d916033d0c6","name":"Hagen Zeitz, LL.M.","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5e6d25234c44b957b67b29d927a01106baae5175005cc8f165a565e625c21ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5e6d25234c44b957b67b29d927a01106baae5175005cc8f165a565e625c21ca?s=96&d=mm&r=g","caption":"Hagen Zeitz, LL.M."},"description":"Rechtsanwalt Hagen Zeitz, LL.M. ist Ansprechpartner f\u00fcr die Bereiche Immobilienrecht, Zwangsvollstreckungsrecht, Gesellschaftsrecht und das allgemeine Zivilrecht. Zu seinen T\u00e4tigkeitsschwerpunkten geh\u00f6rt ferner die Beratung von spanischsprachigen Mandanten in Deutschland, sowie die Unterst\u00fctzung von Mandanten im deutsch-spanischen Rechtsverkehr. Zu seinen Mandanten z\u00e4hlen nationale und internationale KMU\u00b4s, sowie Privatpersonen.","sameAs":["http:\/\/www.wklegal.de\/ansprechpartner\/zeitz.php"]}]}},"_links":{"self":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/posts\/4064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/comments?post=4064"}],"version-history":[{"count":0,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/posts\/4064\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/media?parent=4064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/categories?post=4064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/tags?post=4064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}