{"id":4595,"date":"2013-03-18T08:00:35","date_gmt":"2013-03-18T07:00:35","guid":{"rendered":"https:\/\/www.legalsmart.de\/blog\/?p=4595"},"modified":"2013-03-18T08:00:35","modified_gmt":"2013-03-18T07:00:35","slug":"untervermietung-einblick-in-die-rechtslage","status":"publish","type":"post","link":"https:\/\/www.legalsmart.de\/blog\/untervermietung-einblick-in-die-rechtslage\/","title":{"rendered":"Untervermietung \u2013 Einblick in die Rechtslage 1.Teil"},"content":{"rendered":"<p style=\"text-align: justify\">Teil 1\/2<\/p>\n<p style=\"text-align: justify\">Soll ein Zimmer, eine Wohnung oder ein Grundst\u00fcck untervermietet werden, so stellen sich f\u00fcr den Eigent\u00fcmer (bzw. Vermieter), den Mieter und den Untermieter eine Vielzahl von Fragen.<\/p>\n<p style=\"text-align: justify\">Zun\u00e4chst ist eine wichtige Differenzierung angebracht. Bekannterma\u00dfen gibt es Wohnraummietverh\u00e4ltnisse und sonstige Mietverh\u00e4ltnisse. Dies ist f\u00fcr die Anwendung von <a href=\"https:\/\/dejure.org\/gesetze\/BGB\/553.html\" title=\"&sect; 553 BGB: Gestattung der Gebrauchs&uuml;berlassung an Dritte\">\u00a7 553 BGB<\/a> entscheidend, da diese Vorschrift grunds\u00e4tzlich nur f\u00fcr Wohnungsmietvertr\u00e4ge gilt. Es ist deswegen peinlich darauf zu achten, ob es sich um Wohnungsmiete oder sonstige Mietvertr\u00e4ge handelt, um sicher einsch\u00e4tzen zu k\u00f6nnen, wie die Rechtslage tats\u00e4chlich gestaltet ist.<\/p>\n<p style=\"text-align: justify\">Nach <a href=\"https:\/\/dejure.org\/gesetze\/BGB\/540.html\" title=\"&sect; 540 BGB: Gebrauchs&uuml;berlassung an Dritte\">\u00a7 540 BGB<\/a> muss der Vermieter die \u201eGebrauchs\u00fcberlassung an Dritte\u201c erst erlauben, bevor der Mieter weiteren Personen den Besitz einr\u00e4umen darf. Der (Nichtwohnungs-)Mieter kann diese Erlaubnis normalerweise nicht erzwingen, kann aber bei Versagung k\u00fcndigen.<\/p>\n<p style=\"text-align: justify\">Wird trotz versagter Erlaubnis untervermietet, so kann der Vermieter nach <a href=\"https:\/\/dejure.org\/gesetze\/BGB\/543.html\" title=\"&sect; 543 BGB: Au&szlig;erordentliche fristlose K&uuml;ndigung aus wichtigem Grund\">\u00a7 543 BGB<\/a> zur au\u00dferordentlichen oder zur ordentlichen K\u00fcndigung nach <a href=\"https:\/\/dejure.org\/gesetze\/BGB\/573.html\" title=\"&sect; 573 BGB: Ordentliche K&uuml;ndigung des Vermieters\">\u00a7 573 BGB<\/a> berechtigt sein oder nach <a href=\"https:\/\/dejure.org\/gesetze\/BGB\/541.html\" title=\"&sect; 541 BGB: Unterlassungsklage bei vertragswidrigem Gebrauch\">\u00a7 541 BGB<\/a> auf Unterlassung klagen.<\/p>\n<p style=\"text-align: justify\">So hat also normalerweise \u2013 wenn der Mietvertrag keine Sonderregelung aufweist \u2013 \u00a0der Mieter die Erlaubnis des Vermieters einzuholen, wenn er an eine andere Person ganz oder teilweise untervermieten will. Die Einholung der Erlaubnis soll dem Vermieter n\u00e4mlich Gelegenheit geben, seine Einw\u00e4nde gegen die Untervermietung geltend zu machen, bevor dem Untermieter die R\u00e4ume \u00fcberlassen werden (BayObLG, <a href=\"https:\/\/dejure.org\/dienste\/vernetzung\/rechtsprechung?Text=NJW-RR%201995,%20969\" title=\"BayObLG, 26.04.1995 - REMiet 3\/94: K&uuml;ndigung wegen unbefugter Gebrauchs&uuml;berlassung einer Mietwo...\">NJW-RR 1995, 969<\/a>, 970).<\/p>\n<p style=\"text-align: justify\">Fraglich ist, wann es sich eigentlich um einen Fall von Untervermietung handelt. Wird eine Person in eine Wohnung aufgenommen und soll diese Person die gesamte Wohnung mitbenutzen, so liegt keine Untermiete vor- man sollte hier von einer BGB-Gesellschaft ausgehen. Es fehlt hier an der Ausschlie\u00dflichkeit hinsichtlich der \u00dcbertragung von Besitz an einzelnen Teilen oder der Gesamtheit der R\u00e4ume zu Gunsten dieser Person. Die Erlaubnis zur Gebrauchs\u00fcberlassung ist in solchen Konstellationen aber notwendig.<\/p>\n<p style=\"text-align: justify\">Wenn der Mieter im Rahmen eines Gef\u00e4lligkeitsverh\u00e4ltnisses einem Freund oder anderen bekannten Personen die Mitbenutzung der Wohnung gestattet (bspw. zum Blumengie\u00dfen und Hundef\u00fcttern w\u00e4hrend der urlaubsbedingten Abwesenheit des Mieters), so liegt hierin auch keine unzul\u00e4ssige Gebrauchs\u00fcberlassung oder gar Untervermietung, da diese Personen kein Recht gegen\u00fcber dem Mieter auf Einr\u00e4umung des Besitzes haben. Eine vom Vermieter zu erteilende Erlaubnis wird somit nicht ben\u00f6tigt.<\/p>\n<p style=\"text-align: justify\">Besucher d\u00fcrfen ohne Erlaubnis in den angemieteten R\u00e4umlichkeiten verweilen. Auf die H\u00e4ufigkeit der Besuche soll es nicht ankommen. Auch d\u00fcrften die Besucher einen Haus- und Wohnungsschl\u00fcssel ausgeh\u00e4ndigt erhalten (so das AG Dortmund). Es ist nicht immer ganz leicht den Unterschied zwischen einem zul\u00e4ssigen Besuch und einer erlaubnispflichtigen Leihe zu markieren. Als Besucher ist anzusehen, wer sich wegen besonderer pers\u00f6nlicher Beziehung zum Mieter, ohne Entgelt zu leisten in der Wohnung vor\u00fcbergehend aufh\u00e4lt. Bei einer Besuchsdauer von bis zu 6 Wochen, wird wohl schlechterdings nicht von einer dauerhaften Aufnahme gesprochen werden k\u00f6nnen. Auch kann ein Semesterferienbesuch von 3 Monaten als absolut legitim zu bewerten sein. Die Vermutung der Dauerhaftigkeit der Aufnahme kann hier einfach widerlegt werden.<\/p>\n<p style=\"text-align: justify\">Will ein Mieter f\u00fcr einen Zeitraum, der nicht mehr als Besuchsaufenthalt zu qualifizieren ist, etwa Ehegatten, Kinder, Stiefkinder, Lebenspartner (nach <a href=\"https:\/\/dejure.org\/gesetze\/LPartG\/1.html\" title=\"&sect; 1 LPartG: Lebenspartnerschaft\">\u00a7 1 LPartG<\/a>) oder Pflegepersonal in seinen R\u00e4umlichkeiten aufnehmen, so hat er hierf\u00fcr keine Erlaubnis einzuholen. Dieser privilegierte Personenkreis ist deshalb von Genehmigungserfordernissen freigestellt, da es nach Auffassung weiter Teile der Bev\u00f6lkerung grunds\u00e4tzlich zum normalen Mietgebrauch z\u00e4hlt, diese Personengruppen aufzunehmen. Allerdings d\u00fcrfen den privilegierten Personen die R\u00e4umlichkeiten nur zur Mitbenutzung zur Verf\u00fcgung gestellt werden.<\/p>\n<p style=\"text-align: justify\">Dieser Beitrag wird fortgesetzt.<\/p>\n<p><strong>WK LEGAL<\/strong> ber\u00e4t Vermieter und Mieter, sowie Grundst\u00fcckseigent\u00fcmer, Makler und Hausverwaltungen in s\u00e4mtlichen Bereichen rund um die Themen Miet- und Immobilienrecht und Zwangsvollstreckungsrecht .<\/p>\n<p>Gerne stehen wir Ihnen f\u00fcr Ihre\u00a0 Fragen zur Verf\u00fcgung.\u00a0<a href=\"https:\/\/www.legalsmart.de\/blog\/kontakt-2\">Sprechen Sie uns einfach per E-Mail<\/a>\u00a0an oder nutzen Sie die M\u00f6glichkeit zu einem unverbindlichen und kostenlosen Erstberatungsgespr\u00e4ch unter unserer Telefonnummer 030 \u2013 692051750.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Teil 1\/2 Soll ein Zimmer, eine Wohnung oder ein Grundst\u00fcck untervermietet werden, so stellen sich f\u00fcr den Eigent\u00fcmer (bzw. Vermieter), den Mieter und den Untermieter eine Vielzahl von Fragen. Zun\u00e4chst ist eine wichtige Differenzierung angebracht. Bekannterma\u00dfen gibt es Wohnraummietverh\u00e4ltnisse und sonstige Mietverh\u00e4ltnisse. Dies ist f\u00fcr die Anwendung von \u00a7 553 BGB entscheidend, da diese Vorschrift [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,41],"tags":[104,105,108,117,118,136,390,395,427,573,663,711,867,907,958,959,1011,1016,1209,1287,1324,1330,1421,1428,1441,1508,1656,1884,2139,2291,2479,2480,2507,2526,2799,2841,2854,2988,3324,3542,3580,3582,3583,3594,3724,3785,3803,3988,4001,4005,4006,4008,4016,4084,4116],"class_list":["post-4595","post","type-post","status-publish","format-standard","hentry","category-mietrecht","category-zivilrecht","tag--540-bgb","tag--541-bgb","tag--543-bgb","tag--553-abs-2-bgb","tag--553-bgb","tag--573-bgb","tag-ablehnungsgrunde","tag-abmahnung","tag-abwesend","tag-anspruch-auf-erlaubniserteilung","tag-aufnahme","tag-auserordentliche-kundigung","tag-bayoblg-njw-rr-1995-969-970","tag-berechtigtes-interesses","tag-besuch","tag-besucher","tag-bgh-urteil-vom-2-februar-2011-viii-zr-7410","tag-bgh-urteil-vom-23-november-2005-viii-zr-405","tag-dauerhaftigkeit","tag-dritte-person","tag-ehegatten","tag-eigentumer","tag-erforderlich","tag-erlaubnis","tag-erteilung","tag-fehlende-erlaubnis","tag-gebrauchsuberlassung","tag-hausfrieden","tag-kinder","tag-lebenspartner","tag-mieter","tag-mieterhohung","tag-mietvertrag","tag-mitbenutzung","tag-ordentliche-kundigung","tag-personliche","tag-pflegepersonal","tag-rechtsmissbrauchlich","tag-stiefkinder","tag-unerlaubte-untervermietung","tag-unterlassungsklage","tag-untermiete","tag-untermieter","tag-untervermietung","tag-vermieter","tag-vertragsverletzung","tag-verweigert","tag-wirtschaftliche-grunde","tag-wohngemeinschaft","tag-wohnraummieter","tag-wohnraummietverhaltnis","tag-wohnung","tag-wohnungsschlussel","tag-zimmer","tag-zustimmung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Untervermietung \u2013 Einblick in die Rechtslage 1.Teil<\/title>\n<meta name=\"description\" content=\"Der Artikel besch\u00e4ftigt sich mit der Rechtslage von Unetrvermietungen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.legalsmart.de\/blog\/untervermietung-einblick-in-die-rechtslage\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Untervermietung \u2013 Einblick in die Rechtslage 1.Teil\" \/>\n<meta property=\"og:description\" content=\"Der Artikel besch\u00e4ftigt sich mit der Rechtslage von Unetrvermietungen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.legalsmart.de\/blog\/untervermietung-einblick-in-die-rechtslage\/\" \/>\n<meta property=\"og:site_name\" content=\"LEGAL SMART Online Blog\" \/>\n<meta property=\"article:published_time\" content=\"2013-03-18T07:00:35+00:00\" \/>\n<meta name=\"author\" content=\"Hagen Zeitz, LL.M.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hagen Zeitz, LL.M.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/untervermietung-einblick-in-die-rechtslage\/\",\"url\":\"https:\/\/www.legalsmart.de\/blog\/untervermietung-einblick-in-die-rechtslage\/\",\"name\":\"Untervermietung \u2013 Einblick in die Rechtslage 1.Teil\",\"isPartOf\":{\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#website\"},\"datePublished\":\"2013-03-18T07:00:35+00:00\",\"author\":{\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/d1184d836263690a1bb38d916033d0c6\"},\"description\":\"Der Artikel besch\u00e4ftigt sich mit der Rechtslage von Unetrvermietungen.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.legalsmart.de\/blog\/untervermietung-einblick-in-die-rechtslage\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.legalsmart.de\/blog\/untervermietung-einblick-in-die-rechtslage\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/untervermietung-einblick-in-die-rechtslage\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.legalsmart.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Untervermietung \u2013 Einblick in die Rechtslage 1.Teil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#website\",\"url\":\"https:\/\/www.legalsmart.de\/blog\/\",\"name\":\"LEGAL SMART Online Blog\",\"description\":\"Die innovative Kanzlei\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.legalsmart.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/d1184d836263690a1bb38d916033d0c6\",\"name\":\"Hagen Zeitz, LL.M.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c5e6d25234c44b957b67b29d927a01106baae5175005cc8f165a565e625c21ca?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c5e6d25234c44b957b67b29d927a01106baae5175005cc8f165a565e625c21ca?s=96&d=mm&r=g\",\"caption\":\"Hagen Zeitz, LL.M.\"},\"description\":\"Rechtsanwalt Hagen Zeitz, LL.M. ist Ansprechpartner f\u00fcr die Bereiche Immobilienrecht, Zwangsvollstreckungsrecht, Gesellschaftsrecht und das allgemeine Zivilrecht. Zu seinen T\u00e4tigkeitsschwerpunkten geh\u00f6rt ferner die Beratung von spanischsprachigen Mandanten in Deutschland, sowie die Unterst\u00fctzung von Mandanten im deutsch-spanischen Rechtsverkehr. Zu seinen Mandanten z\u00e4hlen nationale und internationale KMU\u00b4s, sowie Privatpersonen.\",\"sameAs\":[\"http:\/\/www.wklegal.de\/ansprechpartner\/zeitz.php\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Untervermietung \u2013 Einblick in die Rechtslage 1.Teil","description":"Der Artikel besch\u00e4ftigt sich mit der Rechtslage von Unetrvermietungen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.legalsmart.de\/blog\/untervermietung-einblick-in-die-rechtslage\/","og_locale":"de_DE","og_type":"article","og_title":"Untervermietung \u2013 Einblick in die Rechtslage 1.Teil","og_description":"Der Artikel besch\u00e4ftigt sich mit der Rechtslage von Unetrvermietungen.","og_url":"https:\/\/www.legalsmart.de\/blog\/untervermietung-einblick-in-die-rechtslage\/","og_site_name":"LEGAL SMART Online Blog","article_published_time":"2013-03-18T07:00:35+00:00","author":"Hagen Zeitz, LL.M.","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Hagen Zeitz, LL.M.","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.legalsmart.de\/blog\/untervermietung-einblick-in-die-rechtslage\/","url":"https:\/\/www.legalsmart.de\/blog\/untervermietung-einblick-in-die-rechtslage\/","name":"Untervermietung \u2013 Einblick in die Rechtslage 1.Teil","isPartOf":{"@id":"https:\/\/www.legalsmart.de\/blog\/#website"},"datePublished":"2013-03-18T07:00:35+00:00","author":{"@id":"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/d1184d836263690a1bb38d916033d0c6"},"description":"Der Artikel besch\u00e4ftigt sich mit der Rechtslage von Unetrvermietungen.","breadcrumb":{"@id":"https:\/\/www.legalsmart.de\/blog\/untervermietung-einblick-in-die-rechtslage\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.legalsmart.de\/blog\/untervermietung-einblick-in-die-rechtslage\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.legalsmart.de\/blog\/untervermietung-einblick-in-die-rechtslage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.legalsmart.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Untervermietung \u2013 Einblick in die Rechtslage 1.Teil"}]},{"@type":"WebSite","@id":"https:\/\/www.legalsmart.de\/blog\/#website","url":"https:\/\/www.legalsmart.de\/blog\/","name":"LEGAL SMART Online Blog","description":"Die innovative Kanzlei","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.legalsmart.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/d1184d836263690a1bb38d916033d0c6","name":"Hagen Zeitz, LL.M.","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c5e6d25234c44b957b67b29d927a01106baae5175005cc8f165a565e625c21ca?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c5e6d25234c44b957b67b29d927a01106baae5175005cc8f165a565e625c21ca?s=96&d=mm&r=g","caption":"Hagen Zeitz, LL.M."},"description":"Rechtsanwalt Hagen Zeitz, LL.M. ist Ansprechpartner f\u00fcr die Bereiche Immobilienrecht, Zwangsvollstreckungsrecht, Gesellschaftsrecht und das allgemeine Zivilrecht. Zu seinen T\u00e4tigkeitsschwerpunkten geh\u00f6rt ferner die Beratung von spanischsprachigen Mandanten in Deutschland, sowie die Unterst\u00fctzung von Mandanten im deutsch-spanischen Rechtsverkehr. Zu seinen Mandanten z\u00e4hlen nationale und internationale KMU\u00b4s, sowie Privatpersonen.","sameAs":["http:\/\/www.wklegal.de\/ansprechpartner\/zeitz.php"]}]}},"_links":{"self":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/posts\/4595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/comments?post=4595"}],"version-history":[{"count":0,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/posts\/4595\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/media?parent=4595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/categories?post=4595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/tags?post=4595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}