{"id":8784,"date":"2020-07-10T13:00:26","date_gmt":"2020-07-10T11:00:26","guid":{"rendered":"https:\/\/www.legalsmart.de\/blog\/?p=8784"},"modified":"2020-07-10T13:00:29","modified_gmt":"2020-07-10T11:00:29","slug":"wer-muss-die-rueckholung-der-corona-urlauber-bezahlen","status":"publish","type":"post","link":"https:\/\/www.legalsmart.de\/blog\/wer-muss-die-rueckholung-der-corona-urlauber-bezahlen\/","title":{"rendered":"Wer muss die R\u00fcckholung der Corona-Urlauber bezahlen?"},"content":{"rendered":"\n<p>Es ist so weit. Mehr als 250.000 im Ausland gestrandete Menschen wurden aufgrund der Corona-Pandemie mit Hilfe des Ausw\u00e4rtigen Amtes zur\u00fcckgebracht. Die teilweise sp\u00f6ttisch als \u201eMaas\u201c-Airline bezeichneten Fl\u00fcge zur R\u00fcckholung, der in der Welt gestrandeten Bundesb\u00fcrger und EU-B\u00fcrger w\u00e4hrend des Ausbruchs der Corona-Pandemie, werden nun den Zur\u00fcckgeholten in Rechnung gestellt. Wer also damals von einer altruistische Aktion des Ausw\u00e4rtigen Amtes ausgegangen ist, hat sich geirrt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Staffelung der Kosten<\/strong><\/h2>\n\n\n\n<p>Zun\u00e4chst einmal stellt sich aber die Frage, wer jetzt \u00fcberhaupt was f\u00fcr eine Rechnung zu erwarten hat. Hierzu hat das Ausw\u00e4rtige Amt bereits ausgef\u00fchrt, dass man die Kosten je nach Entfernung des Landes in dem man gestrandet ist, sowie \u00fcblicher Ticketpreise f\u00fcr vergleichbare Fl\u00fcge berechnen wird und dies in Pauschalpreiskategorien einordnen wird. So sollen B\u00fcrger, die aus Ozeanien nach Hause geholt wurden den H\u00f6chstsatz von 1000\u20ac f\u00fcr die R\u00fcckholung bezahlen. Wer sich aus Asien oder S\u00fcdamerika zur\u00fcckholen lie\u00df, den erwarten Kosten in H\u00f6he von 600\u20ac und Gestrandete in der Karibik und dem zentralen bis s\u00fcdlichen Afrika 500\u20ac. Mit 200\u20ac zahlt am wenigsten, wer sich von den Kanaren oder Nordafrika ausfliegen lie\u00df.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u201eEs sei nur recht und billig\u201c<\/strong><\/h2>\n\n\n\n<p>Mit diesen Worten hat Au\u00dfenminister Maas die bevorstehende Versendung der Rechnung begr\u00fcndet und betont, dass er nie einen Zweifel an der Beteiligung der Zur\u00fcckgeholten aufkommen lie\u00df. Zus\u00e4tzlich f\u00fchrte er aus, dass es keine Bevorteilung gegen\u00fcber anderen Gestrandeten, die sich selbst um ihre Heimkehr gek\u00fcmmert haben und teils horrenden Preise an die privaten Airlines bezahlen mussten, geben soll. Doch ganz so einfach ist es bei den Juristen nat\u00fcrlich nicht. Es empfiehlt sich daher zun\u00e4chst einmal einen Blick auf die Rechtsgrundlage f\u00fcr die Inanspruchnahme der Passagiere zu werfen. Diese ergibt sich aus \u00a7 5 Konsulargesetz und \u00a7 7 Auslandskostengesetz. Demnach ist der Empf\u00e4nger von erforderlicher Hilfe nach dem Konsulargesetz zum Ersatz der Auslagen verpflichtet. Man hat also die tats\u00e4chlich angefallenen Kosten zu ersetzen. Doch wie ist das mit einer Pauschale vereinbar?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Sind R\u00fcckholpauschalen durch das Ausw\u00e4rtige Amt gerechtfertigt?<\/strong><\/h3>\n\n\n\n<p>Betrachtet man die oben aufgez\u00e4hlten Pauschalen, kommt einem wom\u00f6glich der Gedanke, dass man mit dem vom Ausw\u00e4rtigen Amt angesetzten Betrag schlechter gestellt ist, als wenn man den Flug selbst gebucht h\u00e4tte. M\u00f6glicherweise sind auch die tats\u00e4chlich angefallenen Kosten der individuellen R\u00fcckholaktion niedriger, als man in der Pauschale letztlich in Anspruch genommen wird. W\u00e4hnt man sich in einer der vorbenannten Konstellationen, so muss man dies auch nachweisen. Gelingt einem dieser Nachweis, so ist es also m\u00f6glich den tats\u00e4chlich angefallenen Pauschalbetrag noch zu dr\u00fccken. In der Praxis d\u00fcrfte sich dies aber eher schwierig gestalten, da, von den Beweisschwierigkeiten mal abgesehen, die EU-Kommission verlauten lie\u00df bis zu 75% der Kosten f\u00fcr die R\u00fcckholaktion beizusteuern. Es ist also zu vermuten, dass durch die Pauschalen nur ein Anteil der tats\u00e4chlichen R\u00fcckholkosten \u00fcberhaupt in Rechnung gestellt wurde. Die Konstellation w\u00e4re aber durchaus denkbar, wenn der urspr\u00fcnglich gebuchte R\u00fcckflug pandemiebedingt durch die Airline gestrichen wurde und eben jener gebuchte Flieger pl\u00f6tzlich im Auftrag des Ausw\u00e4rtigen Amtes gestrandete Urlauber zur\u00fcck bringt. Wenn man jetzt f\u00fcr diesen Flug durch die Pauschale mehr bezahlt, als man urspr\u00fcnglich bei der regul\u00e4ren Buchung bezahlt hat, w\u00e4re ein solcher Nachweis erbracht. So ist es durchaus m\u00f6glich, dass ein Karibikurlauber statt der urspr\u00fcnglich gebuchten 250\u20ac f\u00fcr den R\u00fcckflug, auf einmal pauschal 500\u20ac zu entrichten hat obwohl er sich in exakt dem gleichen Flieger befindet, den er f\u00fcr den Tag auch gebucht hatte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Bleibe ich auf den Mehrkosen sitzen?<\/strong><\/h2>\n\n\n\n<p>Um nicht auf den Mehrkosten sitzen zu bleiben kommen zwei verschiedene M\u00f6glichkeiten in Betracht.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Anspr\u00fcche gegen das Ausw\u00e4rtige Amt<\/h3>\n\n\n\n<p>Die erste M\u00f6glichkeit w\u00e4re, wie eben schon angedeutet, dass man dem Ausw\u00e4rtigen Amt entgegenh\u00e4lt, dass der urspr\u00fcngliche R\u00fcckflug billiger gewesen w\u00e4re, als die Pauschale f\u00fcr die R\u00fcckholaktion. Dem Ausw\u00e4rtigen Amt k\u00f6nnte es aber gelingen nachzuweisen, wie viel an Auslagen tats\u00e4chlich f\u00fcr den Flug anteilig angefallen sind und so den Anspruch mit \u00a7 5 Konsulargesetz begr\u00fcnden. In diesem Fall d\u00fcrfte sich der Anspruch gegen das Ausw\u00e4rtige Amt nicht durchsetzen lassen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Anspr\u00fcche gegen die Airline<\/h3>\n\n\n\n<p>Eine andere M\u00f6glichkeit, um die Kosten der R\u00fcckholung nicht selbst tragen zu m\u00fcssen, w\u00e4re es die urspr\u00fcnglich f\u00fcr den R\u00fcckflug beauftragte Airline in Regress zu nehmen. Sollte diese n\u00e4mlich den R\u00fcckflug coronabedingt storniert haben, w\u00e4re dies als R\u00fccktritt vom Vertrag zu werten. Der f\u00fcr den ausgefallenen R\u00fcckflug bereits bezahlte Reise- bzw. Flugpreis ist in einem solchen Fall zwingend von der Airline zur\u00fcckzuerstatten. Dar\u00fcber hinaus k\u00f6nnte sich aber ein Schadensersatz f\u00fcr die Airline ergeben, wobei der Schaden f\u00fcr den Reisenden letztlich die Differenz zwischen dem gebuchten Reisepreis und der angesetzten Pauschale w\u00e4re. Im vorbezeichneten Beispiel, in welchem dem Karibikurlauber von der Airline 250\u20ac zur\u00fcckerstattet wurden und er dann 500\u20ac an das Ausw\u00e4rtige Amt bezahlen muss, bedeutet dies also, dass sein Schadenersatzanspruch gegen\u00fcber der Airline bei 250\u20ac liegen w\u00fcrde. Die Schadensersatzpflicht tritt jedoch nur in bestimmten Konstellationen ein. Hierzu z\u00e4hlen:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Der Flug wurde aus wirtschaftlichen Gr\u00fcnden gestrichen<\/li><li>Es gab noch keine Einschr\u00e4nkungen auf der Flugstrecke (z.B. Grenzschlie\u00dfung, Landeverbot)<\/li><li>Eine Reisewarnung war f\u00fcr das betroffene Gebiet noch nicht ausgesprochen<\/li><\/ul>\n\n\n\n<p>Wenn die Airline dann noch binnen 14 Tagen vor dem geplanten Abflug den Flug gestrichen hat, w\u00e4ren ein Schadensersatz und sogar eine Entsch\u00e4digungspauschale f\u00e4llig.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u201eCoronavirus\u201c gilt als au\u00dfergew\u00f6hnlicher Umstand<\/strong><\/h2>\n\n\n\n<p>Trifft aber keine der oben genannten Konstellationen zu, k\u00e4me k\u00f6nnte tats\u00e4chlich in Betracht kommen, dass man auf den Kosten sitzen bleibt. Der Grund hierf\u00fcr liegt darin, dass die Pandemie als \u201eau\u00dfergew\u00f6hnlicher Umstand\u201c im Sinne der EU-Fluggastrechte-Verordnung 261\/2004 von der EU-Kommission anerkannt wurde. In diesen F\u00e4llen l\u00f6sen Annullierungen oder Versp\u00e4tungen durch die Airline keine Schadensersatzpflicht aus. Die Pflicht zur Erstattung des gestrichenen Fluges besteht aber nat\u00fcrlich weiterhin.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Fazit<\/strong><\/h2>\n\n\n\n<p>Aus rechtlicher Sicht w\u00e4re es also durchaus denkbar, dass zur\u00fcckgeholte Urlauber auf den Kosten der R\u00fcckholung sitzen bleiben und diese selbst bezahlen m\u00fcssen. Zumindest anteilig unter Anrechnung des zur\u00fcckgezahlten Flugpreises des nicht durchgef\u00fchrten Fluges. Sollte aber die Airline im Zusammenhang mit der Stornierung des abgesagten Fluges eine Pflichtverletzung treffen, dann k\u00f6nnten sich hieraus Schadensersatzanspr\u00fcche ergeben, aufgrund derer Urlauber die Kosten der R\u00fcckholung auf die Airline abw\u00e4lzen k\u00f6nnen. Ein genauer Blick auf den Einzelfall kann sich hier also schon mal lohnen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es ist so weit. Mehr als 250.000 im Ausland gestrandete Menschen wurden aufgrund der Corona-Pandemie mit Hilfe des Ausw\u00e4rtigen Amtes zur\u00fcckgebracht. Die teilweise sp\u00f6ttisch als \u201eMaas\u201c-Airline bezeichneten Fl\u00fcge zur R\u00fcckholung, der in der Welt gestrandeten Bundesb\u00fcrger und EU-B\u00fcrger w\u00e4hrend des Ausbruchs der Corona-Pandemie, werden nun den Zur\u00fcckgeholten in Rechnung gestellt. Wer also damals von einer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6047],"tags":[4286,6098,5949,1567,6344,6352,3031,3032,6151,6353,3127,6150,3676,6354],"class_list":["post-8784","post","type-post","status-publish","format-standard","hentry","category-coronavirus","tag-airline","tag-auswaertiges-amt","tag-coronavirus","tag-fluggastrechte","tag-flugpreis","tag-konsulargesetz","tag-reisepreis","tag-reiserecht","tag-rueckholaktion","tag-rueckholung","tag-schadensersatz","tag-urlauber","tag-verbraucher","tag-wer-traegt-die-kosten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wer muss die R\u00fcckholung der Corona-Urlauber bezahlen? | LEGAL SMART Online Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.legalsmart.de\/blog\/wer-muss-die-rueckholung-der-corona-urlauber-bezahlen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wer muss die R\u00fcckholung der Corona-Urlauber bezahlen? | LEGAL SMART Online Blog\" \/>\n<meta property=\"og:description\" content=\"Es ist so weit. Mehr als 250.000 im Ausland gestrandete Menschen wurden aufgrund der Corona-Pandemie mit Hilfe des Ausw\u00e4rtigen Amtes zur\u00fcckgebracht. Die teilweise sp\u00f6ttisch als \u201eMaas\u201c-Airline bezeichneten Fl\u00fcge zur R\u00fcckholung, der in der Welt gestrandeten Bundesb\u00fcrger und EU-B\u00fcrger w\u00e4hrend des Ausbruchs der Corona-Pandemie, werden nun den Zur\u00fcckgeholten in Rechnung gestellt. Wer also damals von einer [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.legalsmart.de\/blog\/wer-muss-die-rueckholung-der-corona-urlauber-bezahlen\/\" \/>\n<meta property=\"og:site_name\" content=\"LEGAL SMART Online Blog\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/guido.kluck\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-10T11:00:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-10T11:00:29+00:00\" \/>\n<meta name=\"author\" content=\"Guido Kluck, LL.M.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/kluck\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Guido Kluck, LL.M.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/wer-muss-die-rueckholung-der-corona-urlauber-bezahlen\/\",\"url\":\"https:\/\/www.legalsmart.de\/blog\/wer-muss-die-rueckholung-der-corona-urlauber-bezahlen\/\",\"name\":\"Wer muss die R\u00fcckholung der Corona-Urlauber bezahlen? | LEGAL SMART Online Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#website\"},\"datePublished\":\"2020-07-10T11:00:26+00:00\",\"dateModified\":\"2020-07-10T11:00:29+00:00\",\"author\":{\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/0869c669bccbe2e56b149b214913b000\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.legalsmart.de\/blog\/wer-muss-die-rueckholung-der-corona-urlauber-bezahlen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.legalsmart.de\/blog\/wer-muss-die-rueckholung-der-corona-urlauber-bezahlen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/wer-muss-die-rueckholung-der-corona-urlauber-bezahlen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.legalsmart.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wer muss die R\u00fcckholung der Corona-Urlauber bezahlen?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#website\",\"url\":\"https:\/\/www.legalsmart.de\/blog\/\",\"name\":\"LEGAL SMART Online Blog\",\"description\":\"Die innovative Kanzlei\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.legalsmart.de\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/0869c669bccbe2e56b149b214913b000\",\"name\":\"Guido Kluck, LL.M.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.legalsmart.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-IMG_2698-e1535879860494-96x96.jpg\",\"contentUrl\":\"https:\/\/www.legalsmart.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-IMG_2698-e1535879860494-96x96.jpg\",\"caption\":\"Guido Kluck, LL.M.\"},\"description\":\"Rechtsanwalt Guido Kluck LL.M. ist Partner der Kanzlei LEGAL SMART am Standort Berlin. Er ist Ansprechpartner f\u00fcr das Recht der neuen Medien sowie f\u00fcr die Bereiche Wettbewerbsrecht, Markenrecht, Urheberrecht, IT-Recht, Vertragsrecht und das Datenschutzrecht (DSGVO).\",\"sameAs\":[\"https:\/\/legalsmart.de\/team_kluck.php\",\"https:\/\/www.facebook.com\/guido.kluck\",\"https:\/\/x.com\/https:\/\/twitter.com\/kluck\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wer muss die R\u00fcckholung der Corona-Urlauber bezahlen? | LEGAL SMART Online Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.legalsmart.de\/blog\/wer-muss-die-rueckholung-der-corona-urlauber-bezahlen\/","og_locale":"de_DE","og_type":"article","og_title":"Wer muss die R\u00fcckholung der Corona-Urlauber bezahlen? | LEGAL SMART Online Blog","og_description":"Es ist so weit. Mehr als 250.000 im Ausland gestrandete Menschen wurden aufgrund der Corona-Pandemie mit Hilfe des Ausw\u00e4rtigen Amtes zur\u00fcckgebracht. Die teilweise sp\u00f6ttisch als \u201eMaas\u201c-Airline bezeichneten Fl\u00fcge zur R\u00fcckholung, der in der Welt gestrandeten Bundesb\u00fcrger und EU-B\u00fcrger w\u00e4hrend des Ausbruchs der Corona-Pandemie, werden nun den Zur\u00fcckgeholten in Rechnung gestellt. Wer also damals von einer [&hellip;]","og_url":"https:\/\/www.legalsmart.de\/blog\/wer-muss-die-rueckholung-der-corona-urlauber-bezahlen\/","og_site_name":"LEGAL SMART Online Blog","article_author":"https:\/\/www.facebook.com\/guido.kluck","article_published_time":"2020-07-10T11:00:26+00:00","article_modified_time":"2020-07-10T11:00:29+00:00","author":"Guido Kluck, LL.M.","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/kluck","twitter_misc":{"Verfasst von":"Guido Kluck, LL.M.","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.legalsmart.de\/blog\/wer-muss-die-rueckholung-der-corona-urlauber-bezahlen\/","url":"https:\/\/www.legalsmart.de\/blog\/wer-muss-die-rueckholung-der-corona-urlauber-bezahlen\/","name":"Wer muss die R\u00fcckholung der Corona-Urlauber bezahlen? | LEGAL SMART Online Blog","isPartOf":{"@id":"https:\/\/www.legalsmart.de\/blog\/#website"},"datePublished":"2020-07-10T11:00:26+00:00","dateModified":"2020-07-10T11:00:29+00:00","author":{"@id":"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/0869c669bccbe2e56b149b214913b000"},"breadcrumb":{"@id":"https:\/\/www.legalsmart.de\/blog\/wer-muss-die-rueckholung-der-corona-urlauber-bezahlen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.legalsmart.de\/blog\/wer-muss-die-rueckholung-der-corona-urlauber-bezahlen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.legalsmart.de\/blog\/wer-muss-die-rueckholung-der-corona-urlauber-bezahlen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.legalsmart.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Wer muss die R\u00fcckholung der Corona-Urlauber bezahlen?"}]},{"@type":"WebSite","@id":"https:\/\/www.legalsmart.de\/blog\/#website","url":"https:\/\/www.legalsmart.de\/blog\/","name":"LEGAL SMART Online Blog","description":"Die innovative Kanzlei","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.legalsmart.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/0869c669bccbe2e56b149b214913b000","name":"Guido Kluck, LL.M.","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.legalsmart.de\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.legalsmart.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-IMG_2698-e1535879860494-96x96.jpg","contentUrl":"https:\/\/www.legalsmart.de\/blog\/wp-content\/uploads\/2018\/09\/cropped-IMG_2698-e1535879860494-96x96.jpg","caption":"Guido Kluck, LL.M."},"description":"Rechtsanwalt Guido Kluck LL.M. ist Partner der Kanzlei LEGAL SMART am Standort Berlin. Er ist Ansprechpartner f\u00fcr das Recht der neuen Medien sowie f\u00fcr die Bereiche Wettbewerbsrecht, Markenrecht, Urheberrecht, IT-Recht, Vertragsrecht und das Datenschutzrecht (DSGVO).","sameAs":["https:\/\/legalsmart.de\/team_kluck.php","https:\/\/www.facebook.com\/guido.kluck","https:\/\/x.com\/https:\/\/twitter.com\/kluck"]}]}},"_links":{"self":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/posts\/8784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/comments?post=8784"}],"version-history":[{"count":3,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/posts\/8784\/revisions"}],"predecessor-version":[{"id":8787,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/posts\/8784\/revisions\/8787"}],"wp:attachment":[{"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/media?parent=8784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/categories?post=8784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.legalsmart.de\/blog\/wp-json\/wp\/v2\/tags?post=8784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}